{"id":5073,"date":"2026-06-15T09:55:49","date_gmt":"2026-06-15T09:55:49","guid":{"rendered":"https:\/\/www.noatumlogistics.com\/mx\/el-canal-de-panama-se-mantiene-estable\/"},"modified":"2026-06-15T12:54:44","modified_gmt":"2026-06-15T12:54:44","slug":"el-canal-de-panama-se-mantiene-estable","status":"publish","type":"post","link":"https:\/\/www.noatumlogistics.com\/mx\/el-canal-de-panama-se-mantiene-estable\/","title":{"rendered":"El Canal de Panam\u00e1 se mantiene estable, pero la planificaci\u00f3n de contingencias sigue siendo clave"},"content":{"rendered":"<p><strong>Para los clientes de transporte mar\u00edtimo que est\u00e9n planificando env\u00edos para el segundo semestre de 2026, las perspectivas del Canal de Panam\u00e1 son m\u00e1s estables de lo que muchos tem\u00edan. No se prev\u00e9 imponer restricciones al tr\u00e1nsito de buques durante el resto de 2026, incluso si El Ni\u00f1o vuelve a intensificar la presi\u00f3n por la sequ\u00eda.<\/strong><\/p>\n<p>Esto ser\u00e1 una noticia positiva para los cargadores afectados por las restricciones derivadas de la sequ\u00eda en Panam\u00e1 en a\u00f1os anteriores, que implicaron una reducci\u00f3n de los cupos de reserva, l\u00edmites de calado m\u00e1s estrictos, retrasos en los buques y un incremento de los costes.<\/p>\n<p>Sin embargo, \u201cno se prev\u00e9n restricciones\u201d no debe confundirse con \u201causencia de riesgo\u201d. Para las empresas que dependen de rutas a trav\u00e9s del Canal de Panam\u00e1 en el tercer y cuarto trimestre, el mensaje debe interpretarse m\u00e1s como una estabilidad prudente que como una certeza absoluta.<\/p>\n<p>&nbsp;<\/p>\n<h3><strong>Por qu\u00e9 las perspectivas son m\u00e1s favorables que antes<\/strong><\/h3>\n<p>La principal raz\u00f3n de esta perspectiva m\u00e1s positiva es la preparaci\u00f3n. Desde 2025, la Autoridad del Canal ha estado implementando medidas de ahorro de agua y ha mantenido los niveles del embalse de Gat\u00fan hist\u00f3ricamente altos, lo que le permite gestionar mejor el riesgo de una menor pluviometr\u00eda a finales de este a\u00f1o.<\/p>\n<p>Tambi\u00e9n hay indicios de que las condiciones de los embalses han mejorado en comparaci\u00f3n con los momentos m\u00e1s cr\u00edticos del reciente periodo de sequ\u00eda. Informes de febrero se\u00f1alaban que el lago Gat\u00fan hab\u00eda alcanzado su nivel operativo m\u00e1ximo, lo que llev\u00f3 a una descarga controlada desde la presa de Gat\u00fan como medida preventiva tras fuertes lluvias.<\/p>\n<p>En conjunto, estos factores sugieren que el canal afronta la segunda mitad de 2026 desde una posici\u00f3n operativa m\u00e1s s\u00f3lida. Esto no elimina por completo la exposici\u00f3n a las condiciones meteorol\u00f3gicas, pero s\u00ed indica que la Autoridad del Canal est\u00e1 tratando de anticiparse a los problemas en lugar de reaccionar cuando las condiciones ya se han deteriorado.<\/p>\n<p>&nbsp;<\/p>\n<h3><strong>Por qu\u00e9 los clientes deben mantenerse alerta<\/strong><\/h3>\n<p>La raz\u00f3n por la que sigue siendo necesario actuar con cautela es sencilla: la amenaza meteorol\u00f3gica no ha desaparecido, y la planificaci\u00f3n sigue teniendo en cuenta posibles escaseces de agua. De hecho, la NOAA prev\u00e9 un 98% de probabilidad de condiciones de El Ni\u00f1o, lo que podr\u00eda aumentar el riesgo de un clima m\u00e1s seco y ejercer presi\u00f3n sobre las operaciones del canal a lo largo del a\u00f1o.<\/p>\n<p>Esto es relevante porque, pese al optimismo de la Autoridad del Canal, los cargadores han comprobado con qu\u00e9 rapidez pueden endurecerse las condiciones en el Canal de Panam\u00e1 cuando disminuye la disponibilidad de agua. En 2023, la Autoridad redujo a\u00fan m\u00e1s los cupos de reserva, que ya eran limitados, y anunci\u00f3 posibles recortes adicionales con el paso del tiempo, mientras que las restricciones derivadas de la sequ\u00eda tambi\u00e9n dieron lugar a limitaciones de calado y a colas m\u00e1s largas.<\/p>\n<p>Para los propietarios de la carga, la principal lecci\u00f3n pr\u00e1ctica es que, incluso cuando el canal sigue operativo, el rendimiento del servicio puede volverse m\u00e1s vol\u00e1til. La disciplina en las reservas, la planificaci\u00f3n de los buques, las ventanas de tr\u00e1nsito y las rutas alternativas cobran a\u00fan mayor importancia cuando existe la posibilidad de cambios operativos derivados de las condiciones meteorol\u00f3gicas durante la temporada alta.<\/p>\n<p>&nbsp;<\/p>\n<h3><strong>Qu\u00e9 implica para la planificaci\u00f3n en el tercer y cuarto trimestre<\/strong><\/h3>\n<p>Para la mayor\u00eda de los cargadores, el enfoque m\u00e1s adecuado para el tercer y cuarto trimestre de 2026 es continuar planificando rutas a trav\u00e9s de Panam\u00e1 cuando tengan sentido desde el punto de vista comercial y operativo, pero haci\u00e9ndolo con mayor disciplina que en un a\u00f1o habitual. Hoy por hoy no hay evidencias claras de que una repetici\u00f3n de las disrupciones anteriores sea inminente; sin embargo, persiste suficiente riesgo meteorol\u00f3gico como para justificar un mayor rigor en la planificaci\u00f3n. Esto implica que algunas prioridades deben ganar peso en la agenda:<\/p>\n<ul>\n<li>Revisar qu\u00e9 env\u00edos est\u00e1n m\u00e1s expuestos a tr\u00e1nsitos por Panam\u00e1, especialmente en el caso de mercanc\u00edas de retail, estacionales o sensibles al tiempo.<\/li>\n<li>Incorporar m\u00e1rgenes realistas en los plazos de entrega en las previsiones para el tercer y cuarto trimestre, por si cambian las condiciones de reserva o los itinerarios de los buques.<\/li>\n<li>Mantener un seguimiento cercano de las actualizaciones de las navieras en cuanto a asignaci\u00f3n de tr\u00e1nsitos, condiciones de calado y cambios en los itinerarios.<\/li>\n<li>Evaluar con antelaci\u00f3n rutas alternativas para la carga que no puede asumir retrasos.<\/li>\n<li>Asegurarse de que los equipos internos de compras, ventas e inventario comprendan que la estabilidad del canal ha mejorado, pero a\u00fan no est\u00e1 completamente garantizada.<\/li>\n<\/ul>\n<p><strong>Si tu cadena de suministro depende de rutas a trav\u00e9s del Canal de Panam\u00e1, ahora es el momento de revisar tu plan de env\u00edos para la segunda mitad del a\u00f1o. Noatum Logistics puede ayudarte a construir una estrategia de transporte mar\u00edtimo m\u00e1s resiliente para el tercer y cuarto trimestre de 2026, con opciones de rutas flexibles, mayor visibilidad de los env\u00edos y el soporte operativo necesario para reducir el riesgo de disrupciones y proteger el rendimiento del servicio.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Para los clientes de transporte mar\u00edtimo que est\u00e9n planificando env\u00edos para el segundo semestre de 2026, las perspectivas del Canal de Panam\u00e1 son m\u00e1s estables de lo que muchos tem\u00edan&#8230;.<\/p>\n","protected":false},"author":9,"featured_media":5074,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[102],"tags":[],"class_list":["post-5073","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-articulos-noticias-logistica"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El Canal de Panam\u00e1 se mantiene estable, pero la planificaci\u00f3n de contingencias sigue siendo clave - M\u00e9xico<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Canal de Panam\u00e1 se mantiene estable, pero la planificaci\u00f3n de contingencias sigue siendo clave - M\u00e9xico\" \/>\n<meta property=\"og:description\" content=\"Para los clientes de transporte mar\u00edtimo que est\u00e9n planificando env\u00edos para el segundo semestre de 2026, las perspectivas del Canal de Panam\u00e1 son m\u00e1s estables de lo que muchos tem\u00edan....\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.noatumlogistics.com\/mx\/el-canal-de-panama-se-mantiene-estable\/\" \/>\n<meta property=\"og:site_name\" content=\"M\u00e9xico\" \/>\n<meta property=\"article:published_time\" content=\"2026-06-15T09:55:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-15T12:54:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.noatumlogistics.com\/mx\/wp-content\/uploads\/sites\/20\/2026\/06\/panama-canal.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1170\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"mjgutierrez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"mjgutierrez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.noatumlogistics.com\\\/mx\\\/el-canal-de-panama-se-mantiene-estable\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.noatumlogistics.com\\\/mx\\\/el-canal-de-panama-se-mantiene-estable\\\/\"},\"author\":{\"name\":\"mjgutierrez\",\"@id\":\"https:\\\/\\\/www.noatumlogistics.com\\\/mx\\\/#\\\/schema\\\/person\\\/a5f444bdf058b79e15d5d0ac335ce513\"},\"headline\":\"El Canal de Panam\u00e1 se mantiene estable, pero la planificaci\u00f3n de contingencias sigue siendo clave\",\"datePublished\":\"2026-06-15T09:55:49+00:00\",\"dateModified\":\"2026-06-15T12:54:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.noatumlogistics.com\\\/mx\\\/el-canal-de-panama-se-mantiene-estable\\\/\"},\"wordCount\":931,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.noatumlogistics.com\\\/mx\\\/el-canal-de-panama-se-mantiene-estable\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.noatumlogistics.com\\\/mx\\\/wp-content\\\/uploads\\\/sites\\\/20\\\/2026\\\/06\\\/panama-canal.png\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.noatumlogistics.com\\\/mx\\\/el-canal-de-panama-se-mantiene-estable\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.noatumlogistics.com\\\/mx\\\/el-canal-de-panama-se-mantiene-estable\\\/\",\"url\":\"https:\\\/\\\/www.noatumlogistics.com\\\/mx\\\/el-canal-de-panama-se-mantiene-estable\\\/\",\"name\":\"El Canal de Panam\u00e1 se mantiene estable, pero la planificaci\u00f3n de contingencias sigue siendo clave - M\u00e9xico\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.noatumlogistics.com\\\/mx\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.noatumlogistics.com\\\/mx\\\/el-canal-de-panama-se-mantiene-estable\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.noatumlogistics.com\\\/mx\\\/el-canal-de-panama-se-mantiene-estable\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.noatumlogistics.com\\\/mx\\\/wp-content\\\/uploads\\\/sites\\\/20\\\/2026\\\/06\\\/panama-canal.png\",\"datePublished\":\"2026-06-15T09:55:49+00:00\",\"dateModified\":\"2026-06-15T12:54:44+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.noatumlogistics.com\\\/mx\\\/#\\\/schema\\\/person\\\/a5f444bdf058b79e15d5d0ac335ce513\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.noatumlogistics.com\\\/mx\\\/el-canal-de-panama-se-mantiene-estable\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.noatumlogistics.com\\\/mx\\\/el-canal-de-panama-se-mantiene-estable\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.noatumlogistics.com\\\/mx\\\/el-canal-de-panama-se-mantiene-estable\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.noatumlogistics.com\\\/mx\\\/wp-content\\\/uploads\\\/sites\\\/20\\\/2026\\\/06\\\/panama-canal.png\",\"contentUrl\":\"https:\\\/\\\/www.noatumlogistics.com\\\/mx\\\/wp-content\\\/uploads\\\/sites\\\/20\\\/2026\\\/06\\\/panama-canal.png\",\"width\":1170,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.noatumlogistics.com\\\/mx\\\/el-canal-de-panama-se-mantiene-estable\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.noatumlogistics.com\\\/mx\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Canal de Panam\u00e1 se mantiene estable, pero la planificaci\u00f3n de contingencias sigue siendo clave\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.noatumlogistics.com\\\/mx\\\/#website\",\"url\":\"https:\\\/\\\/www.noatumlogistics.com\\\/mx\\\/\",\"name\":\"M\u00e9xico\",\"description\":\"Just another Noatum Logistics site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.noatumlogistics.com\\\/mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.noatumlogistics.com\\\/mx\\\/#\\\/schema\\\/person\\\/a5f444bdf058b79e15d5d0ac335ce513\",\"name\":\"mjgutierrez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1eb2c9a609440e74fcaa5729c2a5afcfcba6eb3701b019a67f10340c7b330b09?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1eb2c9a609440e74fcaa5729c2a5afcfcba6eb3701b019a67f10340c7b330b09?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1eb2c9a609440e74fcaa5729c2a5afcfcba6eb3701b019a67f10340c7b330b09?s=96&d=mm&r=g\",\"caption\":\"mjgutierrez\"},\"url\":\"https:\\\/\\\/www.noatumlogistics.com\\\/mx\\\/author\\\/mjgutierrez\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Canal de Panam\u00e1 se mantiene estable, pero la planificaci\u00f3n de contingencias sigue siendo clave - M\u00e9xico","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"es_ES","og_type":"article","og_title":"El Canal de Panam\u00e1 se mantiene estable, pero la planificaci\u00f3n de contingencias sigue siendo clave - M\u00e9xico","og_description":"Para los clientes de transporte mar\u00edtimo que est\u00e9n planificando env\u00edos para el segundo semestre de 2026, las perspectivas del Canal de Panam\u00e1 son m\u00e1s estables de lo que muchos tem\u00edan....","og_url":"https:\/\/www.noatumlogistics.com\/mx\/el-canal-de-panama-se-mantiene-estable\/","og_site_name":"M\u00e9xico","article_published_time":"2026-06-15T09:55:49+00:00","article_modified_time":"2026-06-15T12:54:44+00:00","og_image":[{"width":1170,"height":500,"url":"https:\/\/www.noatumlogistics.com\/mx\/wp-content\/uploads\/sites\/20\/2026\/06\/panama-canal.png","type":"image\/png"}],"author":"mjgutierrez","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"mjgutierrez","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.noatumlogistics.com\/mx\/el-canal-de-panama-se-mantiene-estable\/#article","isPartOf":{"@id":"https:\/\/www.noatumlogistics.com\/mx\/el-canal-de-panama-se-mantiene-estable\/"},"author":{"name":"mjgutierrez","@id":"https:\/\/www.noatumlogistics.com\/mx\/#\/schema\/person\/a5f444bdf058b79e15d5d0ac335ce513"},"headline":"El Canal de Panam\u00e1 se mantiene estable, pero la planificaci\u00f3n de contingencias sigue siendo clave","datePublished":"2026-06-15T09:55:49+00:00","dateModified":"2026-06-15T12:54:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.noatumlogistics.com\/mx\/el-canal-de-panama-se-mantiene-estable\/"},"wordCount":931,"commentCount":0,"image":{"@id":"https:\/\/www.noatumlogistics.com\/mx\/el-canal-de-panama-se-mantiene-estable\/#primaryimage"},"thumbnailUrl":"https:\/\/www.noatumlogistics.com\/mx\/wp-content\/uploads\/sites\/20\/2026\/06\/panama-canal.png","articleSection":["Noticias"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.noatumlogistics.com\/mx\/el-canal-de-panama-se-mantiene-estable\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.noatumlogistics.com\/mx\/el-canal-de-panama-se-mantiene-estable\/","url":"https:\/\/www.noatumlogistics.com\/mx\/el-canal-de-panama-se-mantiene-estable\/","name":"El Canal de Panam\u00e1 se mantiene estable, pero la planificaci\u00f3n de contingencias sigue siendo clave - M\u00e9xico","isPartOf":{"@id":"https:\/\/www.noatumlogistics.com\/mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.noatumlogistics.com\/mx\/el-canal-de-panama-se-mantiene-estable\/#primaryimage"},"image":{"@id":"https:\/\/www.noatumlogistics.com\/mx\/el-canal-de-panama-se-mantiene-estable\/#primaryimage"},"thumbnailUrl":"https:\/\/www.noatumlogistics.com\/mx\/wp-content\/uploads\/sites\/20\/2026\/06\/panama-canal.png","datePublished":"2026-06-15T09:55:49+00:00","dateModified":"2026-06-15T12:54:44+00:00","author":{"@id":"https:\/\/www.noatumlogistics.com\/mx\/#\/schema\/person\/a5f444bdf058b79e15d5d0ac335ce513"},"breadcrumb":{"@id":"https:\/\/www.noatumlogistics.com\/mx\/el-canal-de-panama-se-mantiene-estable\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.noatumlogistics.com\/mx\/el-canal-de-panama-se-mantiene-estable\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.noatumlogistics.com\/mx\/el-canal-de-panama-se-mantiene-estable\/#primaryimage","url":"https:\/\/www.noatumlogistics.com\/mx\/wp-content\/uploads\/sites\/20\/2026\/06\/panama-canal.png","contentUrl":"https:\/\/www.noatumlogistics.com\/mx\/wp-content\/uploads\/sites\/20\/2026\/06\/panama-canal.png","width":1170,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/www.noatumlogistics.com\/mx\/el-canal-de-panama-se-mantiene-estable\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.noatumlogistics.com\/mx\/"},{"@type":"ListItem","position":2,"name":"El Canal de Panam\u00e1 se mantiene estable, pero la planificaci\u00f3n de contingencias sigue siendo clave"}]},{"@type":"WebSite","@id":"https:\/\/www.noatumlogistics.com\/mx\/#website","url":"https:\/\/www.noatumlogistics.com\/mx\/","name":"M\u00e9xico","description":"Just another Noatum Logistics site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.noatumlogistics.com\/mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.noatumlogistics.com\/mx\/#\/schema\/person\/a5f444bdf058b79e15d5d0ac335ce513","name":"mjgutierrez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/1eb2c9a609440e74fcaa5729c2a5afcfcba6eb3701b019a67f10340c7b330b09?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1eb2c9a609440e74fcaa5729c2a5afcfcba6eb3701b019a67f10340c7b330b09?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1eb2c9a609440e74fcaa5729c2a5afcfcba6eb3701b019a67f10340c7b330b09?s=96&d=mm&r=g","caption":"mjgutierrez"},"url":"https:\/\/www.noatumlogistics.com\/mx\/author\/mjgutierrez\/"}]}},"_links":{"self":[{"href":"https:\/\/www.noatumlogistics.com\/mx\/wp-json\/wp\/v2\/posts\/5073","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.noatumlogistics.com\/mx\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.noatumlogistics.com\/mx\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.noatumlogistics.com\/mx\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.noatumlogistics.com\/mx\/wp-json\/wp\/v2\/comments?post=5073"}],"version-history":[{"count":1,"href":"https:\/\/www.noatumlogistics.com\/mx\/wp-json\/wp\/v2\/posts\/5073\/revisions"}],"predecessor-version":[{"id":5076,"href":"https:\/\/www.noatumlogistics.com\/mx\/wp-json\/wp\/v2\/posts\/5073\/revisions\/5076"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.noatumlogistics.com\/mx\/wp-json\/wp\/v2\/media\/5074"}],"wp:attachment":[{"href":"https:\/\/www.noatumlogistics.com\/mx\/wp-json\/wp\/v2\/media?parent=5073"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.noatumlogistics.com\/mx\/wp-json\/wp\/v2\/categories?post=5073"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.noatumlogistics.com\/mx\/wp-json\/wp\/v2\/tags?post=5073"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}