{"id":4478,"date":"2025-03-15T13:57:02","date_gmt":"2025-03-15T12:57:02","guid":{"rendered":"https:\/\/www.noatumlogistics.com\/mx\/americas-cup-en-barcelona-2\/"},"modified":"2025-03-15T13:57:02","modified_gmt":"2025-03-15T12:57:02","slug":"americas-cup-en-barcelona","status":"publish","type":"post","link":"https:\/\/www.noatumlogistics.com\/mx\/americas-cup-en-barcelona\/","title":{"rendered":"Expectaci\u00f3n por la America&#8217;s Cup en Barcelona"},"content":{"rendered":"<p>Noatum Logistics tiene el placer de anunciar su papel principal en la gesti\u00f3n log\u00edstica de tres equipos de renombre que participar\u00e1n en la pr\u00f3xima America&#8217;s Cup, que promete emocionar a Barcelona este agosto. Nuestra asociaci\u00f3n con estos equipos de Estados Unidos, Reino Unido y Francia subraya nuestro compromiso de ofrecer excelencia en todos los aspectos de la industria mar\u00edtima.<\/p>\n<p>La America&#8217;s Cup, conocida como el trofeo m\u00e1s antiguo en la historia del deporte internacional, representa la c\u00faspide de la excelencia en la navegaci\u00f3n a vela. Esta regata atrae a los mejores marineros y equipos de todo el mundo para competir en una serie de emocionantes carreras que ponen a prueba la habilidad, estrategia y resistencia de los competidores. Este a\u00f1o, la Copa llega a Barcelona para su 37\u00aa edici\u00f3n.<\/p>\n<h2><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-19314 size-large\" src=\"https:\/\/www.noatumlogistics.com\/mx\/wp-content\/uploads\/sites\/20\/2025\/04\/IMG-20240325-WA0001--600x450.jpg\" alt=\"\" width=\"600\" height=\"450\" \/><\/h2>\n<p><strong>En un emocionante desarrollo, el avi\u00f3n de carga m\u00e1s grande del mundo, un Antonov, aterriz\u00f3 en el Aeropuerto de Barcelona el 25 de marzo, transportando uno de los preciados yates de carreras de uno de los equipos. Esta notable embarcaci\u00f3n, que mide m\u00e1s de 28 metros de largo y m\u00e1s de 4 metros de alto, fue transportada meticulosamente por tierra, orquestada por Noatum Logistics, desde el Aeropuerto de Barcelona hasta su base en el puerto de Barcelona.<\/strong><\/p>\n<p>Este evento hist\u00f3rico no solo mostr\u00f3 la magnitud de nuestras capacidades log\u00edsticas, sino que tambi\u00e9n destac\u00f3 nuestra dedicaci\u00f3n a la planificaci\u00f3n y ejecuci\u00f3n precisas.<\/p>\n<p>&nbsp;<\/p>\n<h2><strong>Facilitando el transporte de los equipos de la America&#8217;s Cup<\/strong><\/h2>\n<figure id=\"attachment_19261\" aria-describedby=\"caption-attachment-19261\" style=\"width: 600px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-19261 size-large\" src=\"https:\/\/www.noatumlogistics.com\/mx\/wp-content\/uploads\/sites\/20\/2025\/04\/lower-deck-600x450.jpg\" alt=\"\" width=\"600\" height=\"450\" \/><figcaption id=\"caption-attachment-19261\" class=\"wp-caption-text\">GAC Pindar \/ Olly Smith<\/figcaption><\/figure>\n<p>Con a\u00f1os de experiencia en la gesti\u00f3n de operaciones log\u00edsticas complejas, Noatum Logistics se enorgullece de manejar las necesidades log\u00edsticas de equipos de renombre mundial que participan en eventos deportivos de alto perfil como la America&#8217;s Cup. Nuestro compromiso con la excelencia y la eficiencia nos ha posicionado como un socio de confianza en la entrega de soluciones log\u00edsticas personalizadas.<\/p>\n<p>Desde la coordinaci\u00f3n de horarios y rutas hasta la gesti\u00f3n de permisos y el despacho de aduanas, nuestro equipo de expertos se dedica a garantizar un transporte a\u00e9reo, mar\u00edtimo y terrestre fluido y seguro para equipos y activos invaluables.<\/p>\n<p>Durante el \u00faltimo a\u00f1o, hemos proporcionado una gama de servicios a GAC Pindar, la divisi\u00f3n de ocio n\u00e1utico, deportes y eventos del Grupo GAC, con algunos servicios actualmente en curso. El verano pasado, un ch\u00e1rter mar\u00edtimo lleg\u00f3 para uno de los equipos, facilitando la llegada de su embarcaci\u00f3n de entrenamiento junto con varios barcos de apoyo y equipos. Nuestro equipo asegur\u00f3 operaciones fluidas al embarcar a parte del personal en la embarcaci\u00f3n y proporcionar asistencia en el sitio en la terminal para cualquier necesidad adicional.<\/p>\n<p>Para los eventos preliminares en Jeddah y Vilanova, gestionamos el transporte del yate AC40, que ser\u00e1 utilizado por competidores femeninos y j\u00f3venes. Adem\u00e1s, recibimos un barco en Tarragona, optimizando costes y tiempo al entregarlo por v\u00eda mar\u00edtima. Actualmente, estamos proporcionando servicios de alquiler modular para el equipo K-Challenge, suministrando comodidades como vestuarios, ba\u00f1os port\u00e1tiles y duchas para mejorar sus instalaciones.<\/p>\n<p>En Noatum Logistics, entendemos la importancia cr\u00edtica de cada paso en el proceso log\u00edstico y estamos comprometidos a superar las expectativas en cada paso del camino. Nuestra dedicaci\u00f3n a la excelencia operativa y la satisfacci\u00f3n del cliente nos distingue como l\u00edderes en la industria.<\/p>\n<p>&nbsp;<\/p>\n<h2><strong>Noatum Logistics: apoyando la America&#8217;s Cup<\/strong><\/h2>\n<p>En el mundo de la navegaci\u00f3n competitiva, donde la precisi\u00f3n y la fiabilidad son primordiales, GAC ha depositado su confianza en Noatum Logistics para brindar un apoyo log\u00edstico excepcional. Con Noatum Logistics, GAC est\u00e1 aprovechando una ventaja competitiva que los distingue de sus rivales. Cuando supimos que GAC manejar\u00eda este evento, entablamos conversaciones con ellos para asegurar nuestra participaci\u00f3n.<\/p>\n<p>Un aspecto clave que distingue a Noatum Logistics es su extensa red global y experiencia en la gesti\u00f3n de operaciones log\u00edsticas complejas. Con presencia en m\u00e1s de 120 pa\u00edses y un profundo conocimiento de las regulaciones de env\u00edo internacional, Noatum Logistics tiene la capacidad de coordinar sin problemas el transporte de equipos, suministros y personal donde sea que se encuentren en el mundo. Nuestro trabajo con GAC asegura que los equipos puedan centrarse en su entrenamiento y preparaci\u00f3n sin preocuparse por la log\u00edstica de mover su equipo de un lugar a otro.<\/p>\n<p>Gracias a GAC, nuestra presencia en este emocionante proyecto es un testimonio de nuestro compromiso con la excelencia operativa y el servicio al cliente excepcional. En Noatum Logistics, estamos encantados de desempe\u00f1ar un papel activo en el \u00e9xito de la America&#8217;s Cup y esperamos continuar proporcionando soluciones log\u00edsticas para eventos deportivos.<\/p>\n<p>Adem\u00e1s, Noatum Logistics ofrece una amplia gama de servicios de valor a\u00f1adido que mejoran a\u00fan m\u00e1s su propuesta de valor para cualquier cliente, ofreciendo corretaje de aduanas, almacenamiento, transporte de carga, gesti\u00f3n de carga de proyectos y un amplio conjunto de servicios y soluciones. Este enfoque hol\u00edstico asegura que nuestros clientes tengan acceso a los recursos y a la experiencia que necesitan para tener \u00e9xito.[vc_images_carousel images=&#8221;19317,19319,19321&#8243; img_size=&#8221;large&#8221; autoplay=&#8221;yes&#8221; wrap=&#8221;yes&#8221;]Noatum Logistics tiene el placer de anunciar su papel principal en la gesti\u00f3n log\u00edstica de tres equipos de renombre que participar\u00e1n en la pr\u00f3xima America&#8217;s Cup, que promete emocionar a Barcelona este agosto. Nuestra asociaci\u00f3n con estos equipos de Estados Unidos, Reino Unido y Francia subraya nuestro compromiso de ofrecer excelencia en todos los aspectos de la industria mar\u00edtima.<\/p>\n<p>La America&#8217;s Cup, conocida como el trofeo m\u00e1s antiguo en la historia del deporte internacional, representa la c\u00faspide de la excelencia en la navegaci\u00f3n a vela. Esta regata atrae a los mejores marineros y equipos de todo el mundo para competir en una serie de emocionantes carreras que ponen a prueba la habilidad, estrategia y resistencia de los competidores. Este a\u00f1o, la Copa llega a Barcelona para su 37\u00aa edici\u00f3n.<\/p>\n<h2><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-19314 size-large\" src=\"https:\/\/www.noatumlogistics.com\/mx\/wp-content\/uploads\/sites\/20\/2025\/04\/IMG-20240325-WA0001--600x450.jpg\" alt=\"\" width=\"600\" height=\"450\" \/><\/h2>\n<p><strong>En un emocionante desarrollo, el avi\u00f3n de carga m\u00e1s grande del mundo, un Antonov, aterriz\u00f3 en el Aeropuerto de Barcelona el 25 de marzo, transportando uno de los preciados yates de carreras de uno de los equipos. Esta notable embarcaci\u00f3n, que mide m\u00e1s de 28 metros de largo y m\u00e1s de 4 metros de alto, fue transportada meticulosamente por tierra, orquestada por Noatum Logistics, desde el Aeropuerto de Barcelona hasta su base en el puerto de Barcelona.<\/strong><\/p>\n<p>Este evento hist\u00f3rico no solo mostr\u00f3 la magnitud de nuestras capacidades log\u00edsticas, sino que tambi\u00e9n destac\u00f3 nuestra dedicaci\u00f3n a la planificaci\u00f3n y ejecuci\u00f3n precisas.<\/p>\n<p>&nbsp;<\/p>\n<h2><strong>Facilitando el transporte de los equipos de la America&#8217;s Cup<\/strong><\/h2>\n<figure id=\"attachment_19261-2\" aria-describedby=\"caption-attachment-19261-2\" style=\"width: 600px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-19261 size-large\" src=\"https:\/\/www.noatumlogistics.com\/mx\/wp-content\/uploads\/sites\/20\/2025\/04\/lower-deck-600x450.jpg\" alt=\"\" width=\"600\" height=\"450\" \/><figcaption id=\"caption-attachment-19261-2\" class=\"wp-caption-text\">GAC Pindar \/ Olly Smith<\/figcaption><\/figure>\n<p>Con a\u00f1os de experiencia en la gesti\u00f3n de operaciones log\u00edsticas complejas, Noatum Logistics se enorgullece de manejar las necesidades log\u00edsticas de equipos de renombre mundial que participan en eventos deportivos de alto perfil como la America&#8217;s Cup. Nuestro compromiso con la excelencia y la eficiencia nos ha posicionado como un socio de confianza en la entrega de soluciones log\u00edsticas personalizadas.<\/p>\n<p>Desde la coordinaci\u00f3n de horarios y rutas hasta la gesti\u00f3n de permisos y el despacho de aduanas, nuestro equipo de expertos se dedica a garantizar un transporte a\u00e9reo, mar\u00edtimo y terrestre fluido y seguro para equipos y activos invaluables.<\/p>\n<p>Durante el \u00faltimo a\u00f1o, hemos proporcionado una gama de servicios a GAC Pindar, la divisi\u00f3n de ocio n\u00e1utico, deportes y eventos del Grupo GAC, con algunos servicios actualmente en curso. El verano pasado, un ch\u00e1rter mar\u00edtimo lleg\u00f3 para uno de los equipos, facilitando la llegada de su embarcaci\u00f3n de entrenamiento junto con varios barcos de apoyo y equipos. Nuestro equipo asegur\u00f3 operaciones fluidas al embarcar a parte del personal en la embarcaci\u00f3n y proporcionar asistencia en el sitio en la terminal para cualquier necesidad adicional.<\/p>\n<p>Para los eventos preliminares en Jeddah y Vilanova, gestionamos el transporte del yate AC40, que ser\u00e1 utilizado por competidores femeninos y j\u00f3venes. Adem\u00e1s, recibimos un barco en Tarragona, optimizando costes y tiempo al entregarlo por v\u00eda mar\u00edtima. Actualmente, estamos proporcionando servicios de alquiler modular para el equipo K-Challenge, suministrando comodidades como vestuarios, ba\u00f1os port\u00e1tiles y duchas para mejorar sus instalaciones.<\/p>\n<p>En Noatum Logistics, entendemos la importancia cr\u00edtica de cada paso en el proceso log\u00edstico y estamos comprometidos a superar las expectativas en cada paso del camino. Nuestra dedicaci\u00f3n a la excelencia operativa y la satisfacci\u00f3n del cliente nos distingue como l\u00edderes en la industria.<\/p>\n<p>&nbsp;<\/p>\n<h2><strong>Noatum Logistics: apoyando la America&#8217;s Cup<\/strong><\/h2>\n<p>En el mundo de la navegaci\u00f3n competitiva, donde la precisi\u00f3n y la fiabilidad son primordiales, GAC ha depositado su confianza en Noatum Logistics para brindar un apoyo log\u00edstico excepcional. Con Noatum Logistics, GAC est\u00e1 aprovechando una ventaja competitiva que los distingue de sus rivales. Cuando supimos que GAC manejar\u00eda este evento, entablamos conversaciones con ellos para asegurar nuestra participaci\u00f3n.<\/p>\n<p>Un aspecto clave que distingue a Noatum Logistics es su extensa red global y experiencia en la gesti\u00f3n de operaciones log\u00edsticas complejas. Con presencia en m\u00e1s de 120 pa\u00edses y un profundo conocimiento de las regulaciones de env\u00edo internacional, Noatum Logistics tiene la capacidad de coordinar sin problemas el transporte de equipos, suministros y personal donde sea que se encuentren en el mundo. Nuestro trabajo con GAC asegura que los equipos puedan centrarse en su entrenamiento y preparaci\u00f3n sin preocuparse por la log\u00edstica de mover su equipo de un lugar a otro.<\/p>\n<p>Gracias a GAC, nuestra presencia en este emocionante proyecto es un testimonio de nuestro compromiso con la excelencia operativa y el servicio al cliente excepcional. En Noatum Logistics, estamos encantados de desempe\u00f1ar un papel activo en el \u00e9xito de la America&#8217;s Cup y esperamos continuar proporcionando soluciones log\u00edsticas para eventos deportivos.<\/p>\n<p>Adem\u00e1s, Noatum Logistics ofrece una amplia gama de servicios de valor a\u00f1adido que mejoran a\u00fan m\u00e1s su propuesta de valor para cualquier cliente, ofreciendo corretaje de aduanas, almacenamiento, transporte de carga, gesti\u00f3n de carga de proyectos y un amplio conjunto de servicios y soluciones. Este enfoque hol\u00edstico asegura que nuestros clientes tengan acceso a los recursos y a la experiencia que necesitan para tener \u00e9xito.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Noatum Logistics tiene el placer de anunciar su papel principal en la gesti\u00f3n log\u00edstica de tres equipos de renombre que participar\u00e1n en la pr\u00f3xima America&#8217;s Cup, que promete emocionar a&#8230;<\/p>\n","protected":false},"author":9,"featured_media":4495,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[96],"tags":[],"class_list":["post-4478","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-articulos-novedades"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Expectaci\u00f3n por la America&#039;s Cup en Barcelona | Noatum Logistics<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Expectaci\u00f3n por la America&#039;s Cup en Barcelona | Noatum Logistics\" \/>\n<meta property=\"og:description\" content=\"Noatum Logistics tiene el placer de anunciar su papel principal en la gesti\u00f3n log\u00edstica de tres equipos de renombre que participar\u00e1n en la pr\u00f3xima America&#8217;s Cup, que promete emocionar a...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.noatumlogistics.com\/mx\/americas-cup-en-barcelona\/\" \/>\n<meta property=\"og:site_name\" content=\"M\u00e9xico\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-15T12:57:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.noatumlogistics.com\/mx\/wp-content\/uploads\/sites\/20\/2025\/04\/copa-america.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1170\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mjgutierrez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"mjgutierrez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.noatumlogistics.com\\\/mx\\\/americas-cup-en-barcelona\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.noatumlogistics.com\\\/mx\\\/americas-cup-en-barcelona\\\/\"},\"author\":{\"name\":\"mjgutierrez\",\"@id\":\"https:\\\/\\\/www.noatumlogistics.com\\\/mx\\\/#\\\/schema\\\/person\\\/a5f444bdf058b79e15d5d0ac335ce513\"},\"headline\":\"Expectaci\u00f3n por la America&#8217;s Cup en Barcelona\",\"datePublished\":\"2025-03-15T12:57:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.noatumlogistics.com\\\/mx\\\/americas-cup-en-barcelona\\\/\"},\"wordCount\":1788,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.noatumlogistics.com\\\/mx\\\/americas-cup-en-barcelona\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.noatumlogistics.com\\\/mx\\\/wp-content\\\/uploads\\\/sites\\\/20\\\/2025\\\/04\\\/copa-america.jpg\",\"articleSection\":[\"Novedades Noatum Logistics\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.noatumlogistics.com\\\/mx\\\/americas-cup-en-barcelona\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.noatumlogistics.com\\\/mx\\\/americas-cup-en-barcelona\\\/\",\"url\":\"https:\\\/\\\/www.noatumlogistics.com\\\/mx\\\/americas-cup-en-barcelona\\\/\",\"name\":\"Expectaci\u00f3n por la America's Cup en Barcelona | Noatum Logistics\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.noatumlogistics.com\\\/mx\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.noatumlogistics.com\\\/mx\\\/americas-cup-en-barcelona\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.noatumlogistics.com\\\/mx\\\/americas-cup-en-barcelona\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.noatumlogistics.com\\\/mx\\\/wp-content\\\/uploads\\\/sites\\\/20\\\/2025\\\/04\\\/copa-america.jpg\",\"datePublished\":\"2025-03-15T12:57:02+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.noatumlogistics.com\\\/mx\\\/#\\\/schema\\\/person\\\/a5f444bdf058b79e15d5d0ac335ce513\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.noatumlogistics.com\\\/mx\\\/americas-cup-en-barcelona\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.noatumlogistics.com\\\/mx\\\/americas-cup-en-barcelona\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.noatumlogistics.com\\\/mx\\\/americas-cup-en-barcelona\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.noatumlogistics.com\\\/mx\\\/wp-content\\\/uploads\\\/sites\\\/20\\\/2025\\\/04\\\/copa-america.jpg\",\"contentUrl\":\"https:\\\/\\\/www.noatumlogistics.com\\\/mx\\\/wp-content\\\/uploads\\\/sites\\\/20\\\/2025\\\/04\\\/copa-america.jpg\",\"width\":1170,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.noatumlogistics.com\\\/mx\\\/americas-cup-en-barcelona\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.noatumlogistics.com\\\/mx\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Expectaci\u00f3n por la America&#8217;s Cup en Barcelona\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.noatumlogistics.com\\\/mx\\\/#website\",\"url\":\"https:\\\/\\\/www.noatumlogistics.com\\\/mx\\\/\",\"name\":\"M\u00e9xico\",\"description\":\"Just another Noatum Logistics site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.noatumlogistics.com\\\/mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.noatumlogistics.com\\\/mx\\\/#\\\/schema\\\/person\\\/a5f444bdf058b79e15d5d0ac335ce513\",\"name\":\"mjgutierrez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1eb2c9a609440e74fcaa5729c2a5afcfcba6eb3701b019a67f10340c7b330b09?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1eb2c9a609440e74fcaa5729c2a5afcfcba6eb3701b019a67f10340c7b330b09?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1eb2c9a609440e74fcaa5729c2a5afcfcba6eb3701b019a67f10340c7b330b09?s=96&d=mm&r=g\",\"caption\":\"mjgutierrez\"},\"url\":\"https:\\\/\\\/www.noatumlogistics.com\\\/mx\\\/author\\\/mjgutierrez\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Expectaci\u00f3n por la America's Cup en Barcelona | Noatum Logistics","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"es_ES","og_type":"article","og_title":"Expectaci\u00f3n por la America's Cup en Barcelona | Noatum Logistics","og_description":"Noatum Logistics tiene el placer de anunciar su papel principal en la gesti\u00f3n log\u00edstica de tres equipos de renombre que participar\u00e1n en la pr\u00f3xima America&#8217;s Cup, que promete emocionar a...","og_url":"https:\/\/www.noatumlogistics.com\/mx\/americas-cup-en-barcelona\/","og_site_name":"M\u00e9xico","article_published_time":"2025-03-15T12:57:02+00:00","og_image":[{"width":1170,"height":500,"url":"https:\/\/www.noatumlogistics.com\/mx\/wp-content\/uploads\/sites\/20\/2025\/04\/copa-america.jpg","type":"image\/jpeg"}],"author":"mjgutierrez","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"mjgutierrez","Tiempo de lectura":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.noatumlogistics.com\/mx\/americas-cup-en-barcelona\/#article","isPartOf":{"@id":"https:\/\/www.noatumlogistics.com\/mx\/americas-cup-en-barcelona\/"},"author":{"name":"mjgutierrez","@id":"https:\/\/www.noatumlogistics.com\/mx\/#\/schema\/person\/a5f444bdf058b79e15d5d0ac335ce513"},"headline":"Expectaci\u00f3n por la America&#8217;s Cup en Barcelona","datePublished":"2025-03-15T12:57:02+00:00","mainEntityOfPage":{"@id":"https:\/\/www.noatumlogistics.com\/mx\/americas-cup-en-barcelona\/"},"wordCount":1788,"commentCount":0,"image":{"@id":"https:\/\/www.noatumlogistics.com\/mx\/americas-cup-en-barcelona\/#primaryimage"},"thumbnailUrl":"https:\/\/www.noatumlogistics.com\/mx\/wp-content\/uploads\/sites\/20\/2025\/04\/copa-america.jpg","articleSection":["Novedades Noatum Logistics"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.noatumlogistics.com\/mx\/americas-cup-en-barcelona\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.noatumlogistics.com\/mx\/americas-cup-en-barcelona\/","url":"https:\/\/www.noatumlogistics.com\/mx\/americas-cup-en-barcelona\/","name":"Expectaci\u00f3n por la America's Cup en Barcelona | Noatum Logistics","isPartOf":{"@id":"https:\/\/www.noatumlogistics.com\/mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.noatumlogistics.com\/mx\/americas-cup-en-barcelona\/#primaryimage"},"image":{"@id":"https:\/\/www.noatumlogistics.com\/mx\/americas-cup-en-barcelona\/#primaryimage"},"thumbnailUrl":"https:\/\/www.noatumlogistics.com\/mx\/wp-content\/uploads\/sites\/20\/2025\/04\/copa-america.jpg","datePublished":"2025-03-15T12:57:02+00:00","author":{"@id":"https:\/\/www.noatumlogistics.com\/mx\/#\/schema\/person\/a5f444bdf058b79e15d5d0ac335ce513"},"breadcrumb":{"@id":"https:\/\/www.noatumlogistics.com\/mx\/americas-cup-en-barcelona\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.noatumlogistics.com\/mx\/americas-cup-en-barcelona\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.noatumlogistics.com\/mx\/americas-cup-en-barcelona\/#primaryimage","url":"https:\/\/www.noatumlogistics.com\/mx\/wp-content\/uploads\/sites\/20\/2025\/04\/copa-america.jpg","contentUrl":"https:\/\/www.noatumlogistics.com\/mx\/wp-content\/uploads\/sites\/20\/2025\/04\/copa-america.jpg","width":1170,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/www.noatumlogistics.com\/mx\/americas-cup-en-barcelona\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.noatumlogistics.com\/mx\/"},{"@type":"ListItem","position":2,"name":"Expectaci\u00f3n por la America&#8217;s Cup en Barcelona"}]},{"@type":"WebSite","@id":"https:\/\/www.noatumlogistics.com\/mx\/#website","url":"https:\/\/www.noatumlogistics.com\/mx\/","name":"M\u00e9xico","description":"Just another Noatum Logistics site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.noatumlogistics.com\/mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.noatumlogistics.com\/mx\/#\/schema\/person\/a5f444bdf058b79e15d5d0ac335ce513","name":"mjgutierrez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/1eb2c9a609440e74fcaa5729c2a5afcfcba6eb3701b019a67f10340c7b330b09?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1eb2c9a609440e74fcaa5729c2a5afcfcba6eb3701b019a67f10340c7b330b09?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1eb2c9a609440e74fcaa5729c2a5afcfcba6eb3701b019a67f10340c7b330b09?s=96&d=mm&r=g","caption":"mjgutierrez"},"url":"https:\/\/www.noatumlogistics.com\/mx\/author\/mjgutierrez\/"}]}},"_links":{"self":[{"href":"https:\/\/www.noatumlogistics.com\/mx\/wp-json\/wp\/v2\/posts\/4478","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.noatumlogistics.com\/mx\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.noatumlogistics.com\/mx\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.noatumlogistics.com\/mx\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.noatumlogistics.com\/mx\/wp-json\/wp\/v2\/comments?post=4478"}],"version-history":[{"count":1,"href":"https:\/\/www.noatumlogistics.com\/mx\/wp-json\/wp\/v2\/posts\/4478\/revisions"}],"predecessor-version":[{"id":4498,"href":"https:\/\/www.noatumlogistics.com\/mx\/wp-json\/wp\/v2\/posts\/4478\/revisions\/4498"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.noatumlogistics.com\/mx\/wp-json\/wp\/v2\/media\/4495"}],"wp:attachment":[{"href":"https:\/\/www.noatumlogistics.com\/mx\/wp-json\/wp\/v2\/media?parent=4478"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.noatumlogistics.com\/mx\/wp-json\/wp\/v2\/categories?post=4478"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.noatumlogistics.com\/mx\/wp-json\/wp\/v2\/tags?post=4478"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}