{"id":3398,"date":"2022-03-17T09:59:30","date_gmt":"2022-03-17T09:59:30","guid":{"rendered":"https:\/\/www.noatumlogistics.com\/mx\/ventas-de-moda-online-a-punto-de-dispararse\/"},"modified":"2022-12-21T08:48:00","modified_gmt":"2022-12-21T08:48:00","slug":"ventas-de-moda-online-a-punto-de-dispararse","status":"publish","type":"post","link":"https:\/\/www.noatumlogistics.com\/mx\/ventas-de-moda-online-a-punto-de-dispararse\/","title":{"rendered":"Ventas de moda online, \u00a1a punto de dispararse!"},"content":{"rendered":"<p>La pandemia ha cambiado nuestras vidas y ha provocado una ca\u00edda de las ventas de moda online por primera vez en a\u00f1os. Sin embargo, el mercado est\u00e1 listo para remontar y alcanzar los 672.710 millones de d\u00f3lares en 2023.<\/p>\n<p>A continuaci\u00f3n, compartimos lo que buscan los compradores online en t\u00e9rminos de entrega, para ayudarle a lograr el mejor a\u00f1o en materia de ventas.<\/p>\n<p>Aunque los clientes aceptan mejor tener que pagar los gastos de env\u00edo, no quieren pagar de m\u00e1s. Por lo general, el env\u00edo al d\u00eda siguiente en el Reino Unido no deber\u00eda costar m\u00e1s de 6 libras, y el env\u00edo est\u00e1ndar en el Reino Unido no deber\u00eda costar m\u00e1s de 4 libras. Los gigantes de la venta electr\u00f3nica, como ASOS, est\u00e1n marcando el camino y s\u00f3lo ofrecen el env\u00edo gratuito al d\u00eda siguiente a partir de un determinado umbral de ventas.<\/p>\n<p>S\u00f3lo el 16% de los vendedores online personaliza y automatiza las comunicaciones de seguimiento a sus clientes. El seguimiento es algo que ha demostrado ser extremadamente importante para los consumidores en los \u00faltimos a\u00f1os y se ha amplificado durante y despu\u00e9s de la pandemia. El seguimiento es otro punto de contacto entre usted y su cliente, y no hay suficientes empresas que aprovechen esta interacci\u00f3n.<\/p>\n<p>Casi cada segundo, un cliente de la UE abandona su cesta a causa de tiempos de env\u00edo &#8220;desconocidos o m\u00e1s lentos de lo esperado&#8221;.<\/p>\n<p>La informaci\u00f3n sobre la entrega debe mostrarse en varios lugares de su sitio web, nuestras sugerencias son<\/p>\n<ol>\n<li>Un banner en la p\u00e1gina de inicio que indique que realiza entregas en el pa\u00eds del cliente<\/li>\n<li>P\u00e1gina dedicada a la entrega\/devoluciones<\/li>\n<li>P\u00e1gina de preguntas frecuentes<\/li>\n<li>En la p\u00e1gina de pago<\/li>\n<\/ol>\n<p>Mostrar esta informaci\u00f3n en el momento de la compra es lo m\u00e1s eficaz, ya que finaliza el viaje en l\u00ednea de los clientes. S\u00f3lo el 20% de los vendedores electr\u00f3nicos muestran esta informaci\u00f3n en la p\u00e1gina de pago, as\u00ed que adel\u00e1ntese a sus competidores de la moda y h\u00e1galo ahora mismo.<\/p>\n<p>Las devoluciones se consideran con demasiada frecuencia &#8220;ingresos reembolsados&#8221; en lugar de &#8220;p\u00e9rdida de la venta inicial&#8221;. Al comprar en l\u00ednea, se elimina el elemento &#8220;tangible&#8221; de la compra, lo que naturalmente significa un mayor \u00edndice de devoluciones en l\u00ednea frente a la tienda. Si no ofrece un proceso de devoluci\u00f3n adecuado, podr\u00eda estar perdiendo hasta el 50% de su p\u00fablico objetivo. Invierte en marketing, SEO, embalaje, productos, optimizaci\u00f3n del sitio web y luego pierde una venta debido a las devoluciones, \u00a1no cometa este error!<\/p>\n<p>&nbsp;<\/p>\n<h4>Entonces, \u00bfc\u00f3mo puede ayudar Noatum e-Solutions?<\/h4>\n<ol>\n<li>Le ofrecemos m\u00faltiples proveedores de entrega, consolidados en una sola cuenta. Esto combina todo su volumen, fortaleciendo su poder de compra, sin debilitar su oferta.<\/li>\n<li>Software de entrega en la nube, que integra todas sus plataformas de venta con nuestros socios de entrega, para la creaci\u00f3n de etiquetas y la comunicaci\u00f3n de seguimiento sin problemas<\/li>\n<li>Soluci\u00f3n de gesti\u00f3n de devoluciones, que ofrece a sus clientes acceso a un portal con la marca de la empresa, que parece y se siente como parte de su sitio web.<\/li>\n<li>Asociaci\u00f3n estrat\u00e9gica para ayudar al crecimiento y ofrecer asesoramiento experto en log\u00edstica.<\/li>\n<\/ol>\n<p>P\u00f3ngase en contacto con <a href=\"mailto:esolutionsuk@noatumlogistics.com\">esolutionsuk@noatumlogistics.com<\/a> y perm\u00edtanos ayudarle en este panorama de entregas en constante cambio.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Fuentes:<\/strong><\/p>\n<p>https:\/\/www.shopify.co.uk\/enterprise\/ecommerce-fashion-industry<\/p>\n<p>Sendcloud E-commerce Delivery Compass 2021\/2022<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La pandemia ha cambiado nuestras vidas y ha provocado una ca\u00edda de las ventas de moda online por primera vez en a\u00f1os. Sin embargo, el mercado est\u00e1 listo para remontar&#8230;<\/p>\n","protected":false},"author":9,"featured_media":3399,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[120],"tags":[],"class_list":["post-3398","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-articulos-soluciones-ecommerce-3"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ventas de moda online, \u00a1a punto de dispararse! | Noatum Logistics<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ventas de moda online, \u00a1a punto de dispararse! | Noatum Logistics\" \/>\n<meta property=\"og:description\" content=\"La pandemia ha cambiado nuestras vidas y ha provocado una ca\u00edda de las ventas de moda online por primera vez en a\u00f1os. Sin embargo, el mercado est\u00e1 listo para remontar...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.noatumlogistics.com\/mx\/ventas-de-moda-online-a-punto-de-dispararse\/\" \/>\n<meta property=\"og:site_name\" content=\"M\u00e9xico\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-17T09:59:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-21T08:48:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.noatumlogistics.com\/mx\/wp-content\/uploads\/sites\/20\/2022\/12\/17-03.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1170\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mjgutierrez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"mjgutierrez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.noatumlogistics.com\\\/mx\\\/ventas-de-moda-online-a-punto-de-dispararse\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.noatumlogistics.com\\\/mx\\\/ventas-de-moda-online-a-punto-de-dispararse\\\/\"},\"author\":{\"name\":\"mjgutierrez\",\"@id\":\"https:\\\/\\\/www.noatumlogistics.com\\\/mx\\\/#\\\/schema\\\/person\\\/a5f444bdf058b79e15d5d0ac335ce513\"},\"headline\":\"Ventas de moda online, \u00a1a punto de dispararse!\",\"datePublished\":\"2022-03-17T09:59:30+00:00\",\"dateModified\":\"2022-12-21T08:48:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.noatumlogistics.com\\\/mx\\\/ventas-de-moda-online-a-punto-de-dispararse\\\/\"},\"wordCount\":615,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.noatumlogistics.com\\\/mx\\\/ventas-de-moda-online-a-punto-de-dispararse\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.noatumlogistics.com\\\/mx\\\/wp-content\\\/uploads\\\/sites\\\/20\\\/2022\\\/12\\\/17-03.jpg\",\"articleSection\":[\"Soluciones e-commerce\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.noatumlogistics.com\\\/mx\\\/ventas-de-moda-online-a-punto-de-dispararse\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.noatumlogistics.com\\\/mx\\\/ventas-de-moda-online-a-punto-de-dispararse\\\/\",\"url\":\"https:\\\/\\\/www.noatumlogistics.com\\\/mx\\\/ventas-de-moda-online-a-punto-de-dispararse\\\/\",\"name\":\"Ventas de moda online, \u00a1a punto de dispararse! | Noatum Logistics\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.noatumlogistics.com\\\/mx\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.noatumlogistics.com\\\/mx\\\/ventas-de-moda-online-a-punto-de-dispararse\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.noatumlogistics.com\\\/mx\\\/ventas-de-moda-online-a-punto-de-dispararse\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.noatumlogistics.com\\\/mx\\\/wp-content\\\/uploads\\\/sites\\\/20\\\/2022\\\/12\\\/17-03.jpg\",\"datePublished\":\"2022-03-17T09:59:30+00:00\",\"dateModified\":\"2022-12-21T08:48:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.noatumlogistics.com\\\/mx\\\/#\\\/schema\\\/person\\\/a5f444bdf058b79e15d5d0ac335ce513\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.noatumlogistics.com\\\/mx\\\/ventas-de-moda-online-a-punto-de-dispararse\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.noatumlogistics.com\\\/mx\\\/ventas-de-moda-online-a-punto-de-dispararse\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.noatumlogistics.com\\\/mx\\\/ventas-de-moda-online-a-punto-de-dispararse\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.noatumlogistics.com\\\/mx\\\/wp-content\\\/uploads\\\/sites\\\/20\\\/2022\\\/12\\\/17-03.jpg\",\"contentUrl\":\"https:\\\/\\\/www.noatumlogistics.com\\\/mx\\\/wp-content\\\/uploads\\\/sites\\\/20\\\/2022\\\/12\\\/17-03.jpg\",\"width\":1170,\"height\":500,\"caption\":\"fashion sales\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.noatumlogistics.com\\\/mx\\\/ventas-de-moda-online-a-punto-de-dispararse\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.noatumlogistics.com\\\/mx\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Soluciones e-commerce\",\"item\":\"https:\\\/\\\/www.noatumlogistics.com\\\/mx\\\/category\\\/articulos-soluciones-ecommerce-3\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ventas de moda online, \u00a1a punto de dispararse!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.noatumlogistics.com\\\/mx\\\/#website\",\"url\":\"https:\\\/\\\/www.noatumlogistics.com\\\/mx\\\/\",\"name\":\"M\u00e9xico\",\"description\":\"Just another Noatum Logistics site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.noatumlogistics.com\\\/mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.noatumlogistics.com\\\/mx\\\/#\\\/schema\\\/person\\\/a5f444bdf058b79e15d5d0ac335ce513\",\"name\":\"mjgutierrez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1eb2c9a609440e74fcaa5729c2a5afcfcba6eb3701b019a67f10340c7b330b09?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1eb2c9a609440e74fcaa5729c2a5afcfcba6eb3701b019a67f10340c7b330b09?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1eb2c9a609440e74fcaa5729c2a5afcfcba6eb3701b019a67f10340c7b330b09?s=96&d=mm&r=g\",\"caption\":\"mjgutierrez\"},\"url\":\"https:\\\/\\\/www.noatumlogistics.com\\\/mx\\\/author\\\/mjgutierrez\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ventas de moda online, \u00a1a punto de dispararse! | Noatum Logistics","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"es_ES","og_type":"article","og_title":"Ventas de moda online, \u00a1a punto de dispararse! | Noatum Logistics","og_description":"La pandemia ha cambiado nuestras vidas y ha provocado una ca\u00edda de las ventas de moda online por primera vez en a\u00f1os. Sin embargo, el mercado est\u00e1 listo para remontar...","og_url":"https:\/\/www.noatumlogistics.com\/mx\/ventas-de-moda-online-a-punto-de-dispararse\/","og_site_name":"M\u00e9xico","article_published_time":"2022-03-17T09:59:30+00:00","article_modified_time":"2022-12-21T08:48:00+00:00","og_image":[{"width":1170,"height":500,"url":"https:\/\/www.noatumlogistics.com\/mx\/wp-content\/uploads\/sites\/20\/2022\/12\/17-03.jpg","type":"image\/jpeg"}],"author":"mjgutierrez","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"mjgutierrez","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.noatumlogistics.com\/mx\/ventas-de-moda-online-a-punto-de-dispararse\/#article","isPartOf":{"@id":"https:\/\/www.noatumlogistics.com\/mx\/ventas-de-moda-online-a-punto-de-dispararse\/"},"author":{"name":"mjgutierrez","@id":"https:\/\/www.noatumlogistics.com\/mx\/#\/schema\/person\/a5f444bdf058b79e15d5d0ac335ce513"},"headline":"Ventas de moda online, \u00a1a punto de dispararse!","datePublished":"2022-03-17T09:59:30+00:00","dateModified":"2022-12-21T08:48:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.noatumlogistics.com\/mx\/ventas-de-moda-online-a-punto-de-dispararse\/"},"wordCount":615,"commentCount":0,"image":{"@id":"https:\/\/www.noatumlogistics.com\/mx\/ventas-de-moda-online-a-punto-de-dispararse\/#primaryimage"},"thumbnailUrl":"https:\/\/www.noatumlogistics.com\/mx\/wp-content\/uploads\/sites\/20\/2022\/12\/17-03.jpg","articleSection":["Soluciones e-commerce"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.noatumlogistics.com\/mx\/ventas-de-moda-online-a-punto-de-dispararse\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.noatumlogistics.com\/mx\/ventas-de-moda-online-a-punto-de-dispararse\/","url":"https:\/\/www.noatumlogistics.com\/mx\/ventas-de-moda-online-a-punto-de-dispararse\/","name":"Ventas de moda online, \u00a1a punto de dispararse! | Noatum Logistics","isPartOf":{"@id":"https:\/\/www.noatumlogistics.com\/mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.noatumlogistics.com\/mx\/ventas-de-moda-online-a-punto-de-dispararse\/#primaryimage"},"image":{"@id":"https:\/\/www.noatumlogistics.com\/mx\/ventas-de-moda-online-a-punto-de-dispararse\/#primaryimage"},"thumbnailUrl":"https:\/\/www.noatumlogistics.com\/mx\/wp-content\/uploads\/sites\/20\/2022\/12\/17-03.jpg","datePublished":"2022-03-17T09:59:30+00:00","dateModified":"2022-12-21T08:48:00+00:00","author":{"@id":"https:\/\/www.noatumlogistics.com\/mx\/#\/schema\/person\/a5f444bdf058b79e15d5d0ac335ce513"},"breadcrumb":{"@id":"https:\/\/www.noatumlogistics.com\/mx\/ventas-de-moda-online-a-punto-de-dispararse\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.noatumlogistics.com\/mx\/ventas-de-moda-online-a-punto-de-dispararse\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.noatumlogistics.com\/mx\/ventas-de-moda-online-a-punto-de-dispararse\/#primaryimage","url":"https:\/\/www.noatumlogistics.com\/mx\/wp-content\/uploads\/sites\/20\/2022\/12\/17-03.jpg","contentUrl":"https:\/\/www.noatumlogistics.com\/mx\/wp-content\/uploads\/sites\/20\/2022\/12\/17-03.jpg","width":1170,"height":500,"caption":"fashion sales"},{"@type":"BreadcrumbList","@id":"https:\/\/www.noatumlogistics.com\/mx\/ventas-de-moda-online-a-punto-de-dispararse\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.noatumlogistics.com\/mx\/"},{"@type":"ListItem","position":2,"name":"Soluciones e-commerce","item":"https:\/\/www.noatumlogistics.com\/mx\/category\/articulos-soluciones-ecommerce-3\/"},{"@type":"ListItem","position":3,"name":"Ventas de moda online, \u00a1a punto de dispararse!"}]},{"@type":"WebSite","@id":"https:\/\/www.noatumlogistics.com\/mx\/#website","url":"https:\/\/www.noatumlogistics.com\/mx\/","name":"M\u00e9xico","description":"Just another Noatum Logistics site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.noatumlogistics.com\/mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.noatumlogistics.com\/mx\/#\/schema\/person\/a5f444bdf058b79e15d5d0ac335ce513","name":"mjgutierrez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/1eb2c9a609440e74fcaa5729c2a5afcfcba6eb3701b019a67f10340c7b330b09?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1eb2c9a609440e74fcaa5729c2a5afcfcba6eb3701b019a67f10340c7b330b09?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1eb2c9a609440e74fcaa5729c2a5afcfcba6eb3701b019a67f10340c7b330b09?s=96&d=mm&r=g","caption":"mjgutierrez"},"url":"https:\/\/www.noatumlogistics.com\/mx\/author\/mjgutierrez\/"}]}},"_links":{"self":[{"href":"https:\/\/www.noatumlogistics.com\/mx\/wp-json\/wp\/v2\/posts\/3398","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.noatumlogistics.com\/mx\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.noatumlogistics.com\/mx\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.noatumlogistics.com\/mx\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.noatumlogistics.com\/mx\/wp-json\/wp\/v2\/comments?post=3398"}],"version-history":[{"count":0,"href":"https:\/\/www.noatumlogistics.com\/mx\/wp-json\/wp\/v2\/posts\/3398\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.noatumlogistics.com\/mx\/wp-json\/wp\/v2\/media\/3399"}],"wp:attachment":[{"href":"https:\/\/www.noatumlogistics.com\/mx\/wp-json\/wp\/v2\/media?parent=3398"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.noatumlogistics.com\/mx\/wp-json\/wp\/v2\/categories?post=3398"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.noatumlogistics.com\/mx\/wp-json\/wp\/v2\/tags?post=3398"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}