{"id":100,"count":6,"description":"","link":"https:\/\/www.noatumlogistics.com\/mx\/category\/destacadas-es\/","name":"Destacadas","slug":"destacadas-es","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Destacadas Archives - M\u00e9xico<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Destacadas Archives - M\u00e9xico\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.noatumlogistics.com\/mx\/category\/destacadas-es\/\" \/>\n<meta property=\"og:site_name\" content=\"M\u00e9xico\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.noatumlogistics.com\\\/mx\\\/category\\\/destacadas-es\\\/\",\"url\":\"https:\\\/\\\/www.noatumlogistics.com\\\/mx\\\/category\\\/destacadas-es\\\/\",\"name\":\"Destacadas Archives - M\u00e9xico\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.noatumlogistics.com\\\/mx\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.noatumlogistics.com\\\/mx\\\/category\\\/destacadas-es\\\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.noatumlogistics.com\\\/mx\\\/category\\\/destacadas-es\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.noatumlogistics.com\\\/mx\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Destacadas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.noatumlogistics.com\\\/mx\\\/#website\",\"url\":\"https:\\\/\\\/www.noatumlogistics.com\\\/mx\\\/\",\"name\":\"M\u00e9xico\",\"description\":\"Just another Noatum Logistics site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.noatumlogistics.com\\\/mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Destacadas Archives - M\u00e9xico","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"es_ES","og_type":"article","og_title":"Destacadas Archives - M\u00e9xico","og_url":"https:\/\/www.noatumlogistics.com\/mx\/category\/destacadas-es\/","og_site_name":"M\u00e9xico","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.noatumlogistics.com\/mx\/category\/destacadas-es\/","url":"https:\/\/www.noatumlogistics.com\/mx\/category\/destacadas-es\/","name":"Destacadas Archives - M\u00e9xico","isPartOf":{"@id":"https:\/\/www.noatumlogistics.com\/mx\/#website"},"breadcrumb":{"@id":"https:\/\/www.noatumlogistics.com\/mx\/category\/destacadas-es\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/www.noatumlogistics.com\/mx\/category\/destacadas-es\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.noatumlogistics.com\/mx\/"},{"@type":"ListItem","position":2,"name":"Destacadas"}]},{"@type":"WebSite","@id":"https:\/\/www.noatumlogistics.com\/mx\/#website","url":"https:\/\/www.noatumlogistics.com\/mx\/","name":"M\u00e9xico","description":"Just another Noatum Logistics site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.noatumlogistics.com\/mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/www.noatumlogistics.com\/mx\/wp-json\/wp\/v2\/categories\/100","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.noatumlogistics.com\/mx\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.noatumlogistics.com\/mx\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.noatumlogistics.com\/mx\/wp-json\/wp\/v2\/posts?categories=100"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}