{"id":657,"date":"2020-05-07T08:50:24","date_gmt":"2020-05-07T08:50:24","guid":{"rendered":"https:\/\/www.noatumlogistics.com\/mx\/case-studies\/industria-oil-gas\/"},"modified":"2020-06-11T11:11:06","modified_gmt":"2020-06-11T11:11:06","slug":"industria-oil-gas","status":"publish","type":"case_studies","link":"https:\/\/www.noatumlogistics.com\/mx\/case-studies\/industria-oil-gas\/","title":{"rendered":"Caso de \u00e9xito \u2013 Log\u00edstica para la industria de Oil &#038; Gas"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row full_width=&#8221;stretch_row_content_no_spaces&#8221; center_row=&#8221;yes&#8221; css=&#8221;.vc_custom_1584003394864{margin-top: 0px !important;background-image: url(https:\/\/www.noatumlogistics.com\/wp-content\/uploads\/2020\/02\/fondo-directorio-2.jpg?id=9849) !important;background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;}&#8221;][vc_column]<div class=\"zozo-parallax-header\"><div class=\"parallax-header\"><h2 class=\"parallax-title text-center\">Fabricante de unidad de bombeo: los env\u00edos agrupados reducen el uso de contenedores<\/h2><div class=\"parallax-desc default-style text-center\"><p>Nuestro cliente fabrica, da servicio y repara unidades de bombeo para la industria de Oil &amp; Gas en Am\u00e9rica del Norte y Am\u00e9rica del Sur. Las unidades de bombeo se construyen seg\u00fan las especificaciones del cliente en China y luego se env\u00edan a lugaress de perforaci\u00f3n en Am\u00e9rica.<\/p>\n<\/div><\/div><\/div>[\/vc_column][\/vc_row][vc_row][vc_column][vc_raw_html css=&#8221;.vc_custom_1588841283177{margin-bottom: 15px !important;}&#8221;]PGltZyBjbGFzcz0iIiBzcmM9Ii93cC1jb250ZW50L3VwbG9hZHMvMjAyMC8wMy9jaGFsbGVuZ2UtMDEuc3ZnIiB3aWR0aD0iNjBweCIgLz4=[\/vc_raw_html]<div class=\"zozo-parallax-header\"><div class=\"parallax-header\"><h2 class=\"parallax-title text-center\">El reto<\/h2><div class=\"parallax-desc default-style text-center\"><p>Cada unidad pesa aproximadamente 15.000 kg, \u00a0por lo que la compa\u00f1\u00eda ten\u00eda que hacer frente a altos costes en los env\u00edos de las unidades de bombeo procedentes de China.<\/p>\n<\/div><\/div><\/div>[\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row_content&#8221; center_row=&#8221;yes&#8221; typo_style=&#8221;light&#8221; bg_type=&#8221;bg_color&#8221; seperator_enable=&#8221;seperator_enable_value&#8221; seperator_type=&#8221;triangle_svg_seperator&#8221; seperator_svg_height=&#8221;35&#8243; el_class=&#8221;redgradientbg&#8221; bg_color_value=&#8221;#dd9933&#8243; css=&#8221;.vc_custom_1583946305078{padding-top: 100px !important;}&#8221;][vc_column][vc_column_text el_class=&#8221;boxwhy&#8221;]<img decoding=\"async\" class=\"text-center\" src=\"https:\/\/www.noatumlogistics.com\/wp-content\/uploads\/2020\/03\/strategy-01-1.svg\" alt=\"\" width=\"50\" \/><\/p>\n<h2 class=\"parallax-title text-center\">La estrategia<\/h2>\n<p>Noatum Logistics se reuni\u00f3 con el gerente de f\u00e1brica y almac\u00e9n en China y recorri\u00f3 las instalaciones para obtener una comprensi\u00f3n clara de la situaci\u00f3n y estudiar la forma de optimizar los planes de carga. Analizamos la capacidad del almac\u00e9n, las necesidades de refuerzo de cada modelo de bombeo y los requisitos del buque.[\/vc_column_text][vc_column_text el_class=&#8221;boxwhy VinetasRed&#8221;]<img loading=\"lazy\" decoding=\"async\" class=\"text-center\" src=\"\/wp-content\/uploads\/2020\/03\/solution-01-1.svg\" alt=\"\" width=\"60\" height=\"60\" \/><\/p>\n<h2 class=\"parallax-title text-center\">La soluci\u00f3n<\/h2>\n<p>Los planes de optimizaci\u00f3n de carga se basaron en las necesidades de cada modelo de equipo y en el env\u00edo de las unidades de bombeo en lotes. Al manejar cantidades \u00f3ptimas de lotes, el cliente pudo reducir la cantidad de contenedores necesarios para mover varias unidades a la vez.<\/p>\n<p>Adem\u00e1s, esta soluci\u00f3n alter\u00f3 el uso de contrapesos para distribuir el peso de manera m\u00e1s uniforme en el contenedor y reducir as\u00ed el riesgo de cargas inclinadas o desequilibradas.<\/p>\n<p>In addition, the solution altered the use of counterweights to distribute weight more evenly in the container to reduce the risk of leaning or unbalanced loads.[\/vc_column_text][\/vc_column][\/vc_row][vc_row el_class=&#8221;VinetasRed&#8221;][vc_column][vc_raw_html]PGltZyBzcmM9Ii93cC1jb250ZW50L3VwbG9hZHMvMjAyMC8wMy9yZXN1bHQtMDEuc3ZnIiB3aWR0aD0iODBweCIgLz4=[\/vc_raw_html]<div class=\"zozo-parallax-header\"><div class=\"parallax-header\"><h2 class=\"parallax-title text-center\">El resultado<\/h2><div class=\"parallax-desc default-style text-center\"><p>En el modelo inicial enviado con este sistema, Noatum Logistics redujo el uso del contenedor del cliente en un 20% y sus gastos de env\u00edo en un 13%.<\/p>\n<\/div><\/div><\/div>[\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Cada unidad pesa aproximadamente 15.000 kg, \u00a0por lo que la compa\u00f1\u00eda ten\u00eda que hacer frente a altos costes en los env\u00edos de las unidades de bombeo procedentes de China.<\/p>\n","protected":false},"featured_media":662,"template":"","meta":[],"class_list":["post-657","case_studies","type-case_studies","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Caso de \u00e9xito \u2013 Log\u00edstica para la industria de Oil &amp; Gas - M\u00e9xico<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Caso de \u00e9xito \u2013 Log\u00edstica para la industria de Oil &amp; Gas - M\u00e9xico\" \/>\n<meta property=\"og:description\" content=\"Cada unidad pesa aproximadamente 15.000 kg, \u00a0por lo que la compa\u00f1\u00eda ten\u00eda que hacer frente a altos costes en los env\u00edos de las unidades de bombeo procedentes de China.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.noatumlogistics.com\/mx\/case-studies\/industria-oil-gas\/\" \/>\n<meta property=\"og:site_name\" content=\"M\u00e9xico\" \/>\n<meta property=\"article:modified_time\" content=\"2020-06-11T11:11:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.noatumlogistics.com\/mx\/wp-content\/uploads\/sites\/20\/2020\/06\/oilandgas-logistics-case-study-pumping-manufacturer-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.noatumlogistics.com\\\/mx\\\/case-studies\\\/industria-oil-gas\\\/\",\"url\":\"https:\\\/\\\/www.noatumlogistics.com\\\/mx\\\/case-studies\\\/industria-oil-gas\\\/\",\"name\":\"Caso de \u00e9xito \u2013 Log\u00edstica para la industria de Oil & Gas - M\u00e9xico\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.noatumlogistics.com\\\/mx\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.noatumlogistics.com\\\/mx\\\/case-studies\\\/industria-oil-gas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.noatumlogistics.com\\\/mx\\\/case-studies\\\/industria-oil-gas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.noatumlogistics.com\\\/mx\\\/wp-content\\\/uploads\\\/sites\\\/20\\\/2020\\\/06\\\/oilandgas-logistics-case-study-pumping-manufacturer-scaled.jpg\",\"datePublished\":\"2020-05-07T08:50:24+00:00\",\"dateModified\":\"2020-06-11T11:11:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.noatumlogistics.com\\\/mx\\\/case-studies\\\/industria-oil-gas\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.noatumlogistics.com\\\/mx\\\/case-studies\\\/industria-oil-gas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.noatumlogistics.com\\\/mx\\\/case-studies\\\/industria-oil-gas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.noatumlogistics.com\\\/mx\\\/wp-content\\\/uploads\\\/sites\\\/20\\\/2020\\\/06\\\/oilandgas-logistics-case-study-pumping-manufacturer-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.noatumlogistics.com\\\/mx\\\/wp-content\\\/uploads\\\/sites\\\/20\\\/2020\\\/06\\\/oilandgas-logistics-case-study-pumping-manufacturer-scaled.jpg\",\"width\":2560,\"height\":1440,\"caption\":\"oil pump oil rig energy industrial machine for petroleum in the black cumulus clouds before the beginning of a strong storm.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.noatumlogistics.com\\\/mx\\\/case-studies\\\/industria-oil-gas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.noatumlogistics.com\\\/mx\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Case Studies\",\"item\":\"https:\\\/\\\/www.noatumlogistics.com\\\/mx\\\/case-studies\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Caso de \u00e9xito \u2013 Log\u00edstica para la industria de Oil &#038; Gas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.noatumlogistics.com\\\/mx\\\/#website\",\"url\":\"https:\\\/\\\/www.noatumlogistics.com\\\/mx\\\/\",\"name\":\"M\u00e9xico\",\"description\":\"Just another Noatum Logistics site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.noatumlogistics.com\\\/mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Caso de \u00e9xito \u2013 Log\u00edstica para la industria de Oil & Gas - M\u00e9xico","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"es_ES","og_type":"article","og_title":"Caso de \u00e9xito \u2013 Log\u00edstica para la industria de Oil & Gas - M\u00e9xico","og_description":"Cada unidad pesa aproximadamente 15.000 kg, \u00a0por lo que la compa\u00f1\u00eda ten\u00eda que hacer frente a altos costes en los env\u00edos de las unidades de bombeo procedentes de China.","og_url":"https:\/\/www.noatumlogistics.com\/mx\/case-studies\/industria-oil-gas\/","og_site_name":"M\u00e9xico","article_modified_time":"2020-06-11T11:11:06+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/www.noatumlogistics.com\/mx\/wp-content\/uploads\/sites\/20\/2020\/06\/oilandgas-logistics-case-study-pumping-manufacturer-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.noatumlogistics.com\/mx\/case-studies\/industria-oil-gas\/","url":"https:\/\/www.noatumlogistics.com\/mx\/case-studies\/industria-oil-gas\/","name":"Caso de \u00e9xito \u2013 Log\u00edstica para la industria de Oil & Gas - M\u00e9xico","isPartOf":{"@id":"https:\/\/www.noatumlogistics.com\/mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.noatumlogistics.com\/mx\/case-studies\/industria-oil-gas\/#primaryimage"},"image":{"@id":"https:\/\/www.noatumlogistics.com\/mx\/case-studies\/industria-oil-gas\/#primaryimage"},"thumbnailUrl":"https:\/\/www.noatumlogistics.com\/mx\/wp-content\/uploads\/sites\/20\/2020\/06\/oilandgas-logistics-case-study-pumping-manufacturer-scaled.jpg","datePublished":"2020-05-07T08:50:24+00:00","dateModified":"2020-06-11T11:11:06+00:00","breadcrumb":{"@id":"https:\/\/www.noatumlogistics.com\/mx\/case-studies\/industria-oil-gas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.noatumlogistics.com\/mx\/case-studies\/industria-oil-gas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.noatumlogistics.com\/mx\/case-studies\/industria-oil-gas\/#primaryimage","url":"https:\/\/www.noatumlogistics.com\/mx\/wp-content\/uploads\/sites\/20\/2020\/06\/oilandgas-logistics-case-study-pumping-manufacturer-scaled.jpg","contentUrl":"https:\/\/www.noatumlogistics.com\/mx\/wp-content\/uploads\/sites\/20\/2020\/06\/oilandgas-logistics-case-study-pumping-manufacturer-scaled.jpg","width":2560,"height":1440,"caption":"oil pump oil rig energy industrial machine for petroleum in the black cumulus clouds before the beginning of a strong storm."},{"@type":"BreadcrumbList","@id":"https:\/\/www.noatumlogistics.com\/mx\/case-studies\/industria-oil-gas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.noatumlogistics.com\/mx\/"},{"@type":"ListItem","position":2,"name":"Case Studies","item":"https:\/\/www.noatumlogistics.com\/mx\/case-studies\/"},{"@type":"ListItem","position":3,"name":"Caso de \u00e9xito \u2013 Log\u00edstica para la industria de Oil &#038; Gas"}]},{"@type":"WebSite","@id":"https:\/\/www.noatumlogistics.com\/mx\/#website","url":"https:\/\/www.noatumlogistics.com\/mx\/","name":"M\u00e9xico","description":"Just another Noatum Logistics site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.noatumlogistics.com\/mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/www.noatumlogistics.com\/mx\/wp-json\/wp\/v2\/case_studies\/657","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.noatumlogistics.com\/mx\/wp-json\/wp\/v2\/case_studies"}],"about":[{"href":"https:\/\/www.noatumlogistics.com\/mx\/wp-json\/wp\/v2\/types\/case_studies"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.noatumlogistics.com\/mx\/wp-json\/wp\/v2\/media\/662"}],"wp:attachment":[{"href":"https:\/\/www.noatumlogistics.com\/mx\/wp-json\/wp\/v2\/media?parent=657"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}