{"id":2748,"date":"2020-05-14T08:31:16","date_gmt":"2020-05-14T08:31:16","guid":{"rendered":"https:\/\/www.noatumlogistics.com\/esp\/noatum-logistics\/historia\/"},"modified":"2021-06-18T16:32:40","modified_gmt":"2021-06-18T16:32:40","slug":"historia","status":"publish","type":"page","link":"https:\/\/www.noatumlogistics.com\/esp\/noatum-logistics\/historia\/","title":{"rendered":"Historia"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row disable_element=&#8221;yes&#8221; center_row=&#8221;yes&#8221;][vc_column]<div class=\"smile-icon-timeline-wrap csstime   \"    data-time_sep_color=&quot;#dd3333&quot; style=\"\"><div class=\"timeline-line \" style=\"border-right-color:#dd3333;\"><span><\/span><\/div><div class=\"timeline-wrapper\"><div class=\"timeline-block \"><div class=\"timeline-dot\"><\/div><div class=\"ult-timeline-arrow\"><s><\/s><l><\/l><\/div><div class=\"timeline-icon-block\"><div class=\"ult-timeline-icon tl-icon-no-bg\" style=\"   \"><\/div> <!-- icon --><\/div><div class=\"timeline-header-block\" >\n\t\t\t\t\t\t\t<div id=\"timeline-item-1290\" class=\"timeline-header\" style=\"\"><h5 class=\"ult-timeline-title ult-responsive\"  data-ultimate-target='#timeline-item-1290 .ult-timeline-title'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"\">Fundaci\u00f3n del grupo<\/h5><div class=\"ult-responsive timeline-item-spt\"  data-ultimate-target='#timeline-item-1290 .timeline-item-spt'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"\"><\/div><\/div> <!-- header --><\/div><\/div><div class=\"timeline-block \"><div class=\"timeline-dot\"><\/div><div class=\"ult-timeline-arrow\"><s><\/s><l><\/l><\/div><div class=\"timeline-icon-block\"><div class=\"ult-timeline-icon tl-icon-no-bg\" style=\"   \"><\/div> <!-- icon --><\/div><div class=\"timeline-header-block\" >\n\t\t\t\t\t\t\t<div id=\"timeline-item-9753\" class=\"timeline-header\" style=\"\"><h3 class=\"ult-timeline-title ult-responsive\"  data-ultimate-target='#timeline-item-9753 .ult-timeline-title'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"\">fasdfadsfasd<\/h3><div class=\"ult-responsive timeline-item-spt\"  data-ultimate-target='#timeline-item-9753 .timeline-item-spt'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"\">asdfasdfdsafasdf<\/div><\/div> <!-- header --><\/div><\/div><div class=\"timeline-block \"><div class=\"timeline-dot\"><\/div><div class=\"ult-timeline-arrow\"><s><\/s><l><\/l><\/div><div class=\"timeline-icon-block\"><div class=\"ult-timeline-icon tl-icon-no-bg\" style=\"   \"><\/div> <!-- icon --><\/div><div class=\"timeline-header-block\" >\n\t\t\t\t\t\t\t<div id=\"timeline-item-8439\" class=\"timeline-header\" style=\"\"><h3 class=\"ult-timeline-title ult-responsive\"  data-ultimate-target='#timeline-item-8439 .ult-timeline-title'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"\">fasdfadsfasd<\/h3><div class=\"ult-responsive timeline-item-spt\"  data-ultimate-target='#timeline-item-8439 .timeline-item-spt'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"\">asdfasdfdsafasdf<\/div><\/div> <!-- header --><\/div><\/div><\/div><div class=\"timeline-feature-item feat-item  \"><div class=\"feat-dot \"><div class=\"timeline-dot\"><\/div><\/div><div class=\"ult-timeline-arrow \"><s><\/s><l><\/l><\/div><div class=\"timeline-icon-block\"><div class=\"ult-timeline-icon tl-icon-no-bg\" style=\"   \"><\/div> <!-- icon --><\/div><div class=\"timeline-header-block\" >\n\t\t\t\t\t\t\t<div class=\"timeline-header\" id=\"timeline-featured-1969\"  style=\"\"><h3\n\t\t\t class=\"ult-timeline-title ult-responsive\"   data-ultimate-target='#timeline-featured-1969 .ult-timeline-title'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"\">featured<\/h3><div class=\"ult-responsive custom-lht\"  data-ultimate-target='#timeline-featured-1969 .custom-lht'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"\"><\/div><\/div> <!-- header --><\/div><\/div><div class=\"timeline-wrapper \"><\/div>\n\t\t\t\t<div id=\"timeline-seperator-3059\" class=\"timeline-separator-text \" data-sep-col=\"\" data-sep-bg-col=\"\"><span class=\"sep-text ult-responsive\"  data-ultimate-target='#timeline-seperator-3059 .sep-text'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"border-style:solid;border-width:1px;border-radius:5px;\">2016<\/span><\/div><div class=\"timeline-wrapper \"><\/div><\/div>[vc_row_inner][vc_column_inner width=&#8221;1\/2&#8243;]<div class=\"zozo-parallax-header destacado\"><div class=\"parallax-header\"><h2 class=\"parallax-title text-left\" style=\"font-size:30px;\">Entre los 50 principales freight forwarders del mundo<\/h2><div class=\"parallax-desc default-style text-left\"><h4>Noatum Logistics es una empresa l\u00edder en Supply Chain Mangement con cobertura global, especialista en freight management, international supply chain management, log\u00edstica integral, log\u00edstica de proyectos, eSolutions, aduanas y compliance.<\/h4>\n<\/div><\/div><\/div>[\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243; css=&#8221;.vc_custom_1585069181387{padding-top: 75px !important;}&#8221;][vc_column_text]As an innovative logistics provider, we offer specific, integrated, complex and value-added solutions for our clients&#8217; supply chains, while maintaining long-term relationships built on trust and confidence to guarantee success.<\/p>\n<p>Our team of over 1,700 experienced professionals always puts our motto of &#8220;Excellence in Logistics Services&#8221; into practice by providing high quality services to our customers.[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row center_row=&#8221;yes&#8221;][vc_column][vc_column_text]<img decoding=\"async\" class=\"alignnone size-full wp-image-14660\" src=\"https:\/\/www.noatumlogistics.com\/wp-content\/uploads\/2020\/07\/historia.svg\" alt=\"\" \/>[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row disable_element=&#8221;yes&#8221; center_row=&#8221;yes&#8221;][vc_column][vc_row_inner][vc_column_inner width=&#8221;1\/2&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243; css=&#8221;.vc_custom_1585069181387{padding-top: 75px !important;}&#8221;][vc_column_text]As an innovative logistics provider, we offer specific, integrated, complex and value-added solutions for our clients&#8217; supply chains, while maintaining long-term relationships built&#8230;<\/p>\n","protected":false},"author":9,"featured_media":0,"parent":129,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template-fullwidth.php","meta":{"footnotes":""},"class_list":["post-2748","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Historia de Noatum Logistics, freight forwarder global<\/title>\n<meta name=\"description\" content=\"Noatum Logistics es un freight forwarder l\u00edder en log\u00edstica, transporte internacional y aduanas. Con 97 oficinas y presencia en 25 pa\u00edses\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.noatumlogistics.com\/esp\/noatum-logistics\/historia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Historia de Noatum Logistics, freight forwarder global\" \/>\n<meta property=\"og:description\" content=\"Noatum Logistics es un freight forwarder l\u00edder en log\u00edstica, transporte internacional y aduanas. Con 97 oficinas y presencia en 25 pa\u00edses\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.noatumlogistics.com\/esp\/noatum-logistics\/historia\/\" \/>\n<meta property=\"og:site_name\" content=\"Espa\u00f1a\" \/>\n<meta property=\"article:modified_time\" content=\"2021-06-18T16:32:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.noatumlogistics.com\/wp-content\/uploads\/2020\/07\/historia.svg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.noatumlogistics.com\\\/esp\\\/noatum-logistics\\\/historia\\\/\",\"url\":\"https:\\\/\\\/www.noatumlogistics.com\\\/esp\\\/noatum-logistics\\\/historia\\\/\",\"name\":\"Historia de Noatum Logistics, freight forwarder global\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.noatumlogistics.com\\\/esp\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.noatumlogistics.com\\\/esp\\\/noatum-logistics\\\/historia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.noatumlogistics.com\\\/esp\\\/noatum-logistics\\\/historia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.noatumlogistics.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/historia.svg\",\"datePublished\":\"2020-05-14T08:31:16+00:00\",\"dateModified\":\"2021-06-18T16:32:40+00:00\",\"description\":\"Noatum Logistics es un freight forwarder l\u00edder en log\u00edstica, transporte internacional y aduanas. Con 97 oficinas y presencia en 25 pa\u00edses\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.noatumlogistics.com\\\/esp\\\/noatum-logistics\\\/historia\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.noatumlogistics.com\\\/esp\\\/noatum-logistics\\\/historia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.noatumlogistics.com\\\/esp\\\/noatum-logistics\\\/historia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.noatumlogistics.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/historia.svg\",\"contentUrl\":\"https:\\\/\\\/www.noatumlogistics.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/historia.svg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.noatumlogistics.com\\\/esp\\\/noatum-logistics\\\/historia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.noatumlogistics.com\\\/esp\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Historia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.noatumlogistics.com\\\/esp\\\/#website\",\"url\":\"https:\\\/\\\/www.noatumlogistics.com\\\/esp\\\/\",\"name\":\"Espa\u00f1a\",\"description\":\"Just another Noatum Logistics site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.noatumlogistics.com\\\/esp\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Historia de Noatum Logistics, freight forwarder global","description":"Noatum Logistics es un freight forwarder l\u00edder en log\u00edstica, transporte internacional y aduanas. Con 97 oficinas y presencia en 25 pa\u00edses","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.noatumlogistics.com\/esp\/noatum-logistics\/historia\/","og_locale":"es_ES","og_type":"article","og_title":"Historia de Noatum Logistics, freight forwarder global","og_description":"Noatum Logistics es un freight forwarder l\u00edder en log\u00edstica, transporte internacional y aduanas. Con 97 oficinas y presencia en 25 pa\u00edses","og_url":"https:\/\/www.noatumlogistics.com\/esp\/noatum-logistics\/historia\/","og_site_name":"Espa\u00f1a","article_modified_time":"2021-06-18T16:32:40+00:00","og_image":[{"url":"https:\/\/www.noatumlogistics.com\/wp-content\/uploads\/2020\/07\/historia.svg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.noatumlogistics.com\/esp\/noatum-logistics\/historia\/","url":"https:\/\/www.noatumlogistics.com\/esp\/noatum-logistics\/historia\/","name":"Historia de Noatum Logistics, freight forwarder global","isPartOf":{"@id":"https:\/\/www.noatumlogistics.com\/esp\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.noatumlogistics.com\/esp\/noatum-logistics\/historia\/#primaryimage"},"image":{"@id":"https:\/\/www.noatumlogistics.com\/esp\/noatum-logistics\/historia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.noatumlogistics.com\/wp-content\/uploads\/2020\/07\/historia.svg","datePublished":"2020-05-14T08:31:16+00:00","dateModified":"2021-06-18T16:32:40+00:00","description":"Noatum Logistics es un freight forwarder l\u00edder en log\u00edstica, transporte internacional y aduanas. Con 97 oficinas y presencia en 25 pa\u00edses","breadcrumb":{"@id":"https:\/\/www.noatumlogistics.com\/esp\/noatum-logistics\/historia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.noatumlogistics.com\/esp\/noatum-logistics\/historia\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.noatumlogistics.com\/esp\/noatum-logistics\/historia\/#primaryimage","url":"https:\/\/www.noatumlogistics.com\/wp-content\/uploads\/2020\/07\/historia.svg","contentUrl":"https:\/\/www.noatumlogistics.com\/wp-content\/uploads\/2020\/07\/historia.svg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.noatumlogistics.com\/esp\/noatum-logistics\/historia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.noatumlogistics.com\/esp\/"},{"@type":"ListItem","position":2,"name":"Historia"}]},{"@type":"WebSite","@id":"https:\/\/www.noatumlogistics.com\/esp\/#website","url":"https:\/\/www.noatumlogistics.com\/esp\/","name":"Espa\u00f1a","description":"Just another Noatum Logistics site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.noatumlogistics.com\/esp\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/www.noatumlogistics.com\/esp\/wp-json\/wp\/v2\/pages\/2748","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.noatumlogistics.com\/esp\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.noatumlogistics.com\/esp\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.noatumlogistics.com\/esp\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.noatumlogistics.com\/esp\/wp-json\/wp\/v2\/comments?post=2748"}],"version-history":[{"count":0,"href":"https:\/\/www.noatumlogistics.com\/esp\/wp-json\/wp\/v2\/pages\/2748\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/www.noatumlogistics.com\/esp\/wp-json\/wp\/v2\/pages\/129"}],"wp:attachment":[{"href":"https:\/\/www.noatumlogistics.com\/esp\/wp-json\/wp\/v2\/media?parent=2748"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}