{"id":674,"date":"2020-05-06T14:26:11","date_gmt":"2020-05-06T14:26:11","guid":{"rendered":"https:\/\/www.noatumlogistics.com\/esp\/case-studies\/retail-logistics-lg-harris\/"},"modified":"2021-05-27T14:36:42","modified_gmt":"2021-05-27T14:36:42","slug":"retail-logistics-lg-harris","status":"publish","type":"case_studies","link":"https:\/\/www.noatumlogistics.com\/esp\/case-studies\/retail-logistics-lg-harris\/","title":{"rendered":"Caso de \u00e9xito \u2013 Log\u00edstica para retail: LG Harris"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row full_width=&#8221;stretch_row_content_no_spaces&#8221; center_row=&#8221;yes&#8221; css=&#8221;.vc_custom_1584003394864{margin-top: 0px !important;background-image: url(https:\/\/www.noatumlogistics.com\/wp-content\/uploads\/2020\/02\/fondo-directorio-2.jpg?id=9849) !important;background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;}&#8221;][vc_column][vc_raw_html css=&#8221;.vc_custom_1588776046647{margin-bottom: 15px !important;}&#8221;]PGltZyBjbGFzcz0iIiBzcmM9Ii93cC1jb250ZW50L3VwbG9hZHMvMjAyMC8wNC9MRy1IYXJyaXMtbG9nby5wbmciIHdpZHRoPSI4MHB4IiAvPg==[\/vc_raw_html]<div class=\"zozo-parallax-header\"><div class=\"parallax-header\"><h2 class=\"parallax-title text-center\">Fabricante de productos de decoraci\u00f3n<\/h2><div class=\"parallax-desc default-style text-center\"><p>Fundada en 1928, Harris es un fabricante de internacional de productos de decoraci\u00f3n de f\u00e1cil manejo, usando algunos de los mejores materiales. Hoy, Harris es una compa\u00f1\u00eda l\u00edder por su calidad e innovaci\u00f3n, suministrando con \u00e9xito sus productos a millones de decoradores en todo el mundo. Con su intenso programa de desarrollo de producto, Harris contin\u00faa demostrando sus capacidades con un dise\u00f1o l\u00edder en el mercado de un modo que consigue que la decoraci\u00f3n sea m\u00e1s f\u00e1cil, agradable y efectiva.<\/p>\n<\/div><\/div><\/div>[\/vc_column][\/vc_row][vc_row][vc_column][vc_raw_html css=&#8221;.vc_custom_1588776036672{margin-bottom: 15px !important;}&#8221;]PGltZyBjbGFzcz0iIiB3aWR0aD0iNjBweCIgc3JjPSIvd3AtY29udGVudC91cGxvYWRzLzIwMjAvMDMvY2hhbGxlbmdlLTAxLnN2ZyI+[\/vc_raw_html]<div class=\"zozo-parallax-header\"><div class=\"parallax-header\"><h2 class=\"parallax-title text-center\">El reto<\/h2><div class=\"parallax-desc default-style text-center\"><p>Al estudiar las necesidades de la cadena de suministro de LG Harris, Noatum Logistics identific\u00f3 r\u00e1pidamente que sus t\u00e9rminos de compra eran CIF (Cost \u2013 Insurance &#8211; Freight) en la mayor\u00eda de su base de suministro. Esto le imped\u00eda la transparencia total en los env\u00edos hasta que las mercanc\u00edas llegaban al puerto. Contabilizar m\u00e1s de 1.000 TEU por a\u00f1o supon\u00eda un gran dolor de cabeza. El modelo de la cadena de suministro era completamente reactivo con poca o ninguna gesti\u00f3n de informes o indicadores clave de rendimiento (KPI). Esto supon\u00eda altos cargos por demora, inventario entrante y dificultades del control de stocks en el centro de distribuci\u00f3n LG Harris ubicado en Midlands (Reino Unido).<\/p>\n<\/div><\/div><\/div>[\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row_content&#8221; center_row=&#8221;yes&#8221; typo_style=&#8221;light&#8221; bg_type=&#8221;bg_color&#8221; seperator_enable=&#8221;seperator_enable_value&#8221; seperator_type=&#8221;triangle_svg_seperator&#8221; seperator_svg_height=&#8221;35&#8243; el_class=&#8221;redgradientbg&#8221; bg_color_value=&#8221;#dd9933&#8243; css=&#8221;.vc_custom_1583946305078{padding-top: 100px !important;}&#8221;][vc_column][vc_column_text el_class=&#8221;boxwhy&#8221;]<img decoding=\"async\" class=\"text-center\" src=\"https:\/\/www.noatumlogistics.com\/wp-content\/uploads\/2020\/03\/strategy-01-1.svg\" alt=\"\" width=\"50\" \/><\/p>\n<h2 class=\"parallax-title text-center\">La estrategia<\/h2>\n<p>LG Harris seleccion\u00f3 a Noatum Logistics como freight forwarder preferente. Juntos, desarrollamos r\u00e1pidamente una estrategia para mejorar su cadena de suministro. Uno de los motivos para que el cliente nos seleccionase fue nuestra capacidad y experiencia en el sector minorista, ambas cr\u00edticas para el crecimiento del negocio LG Harris. Recuperar el control de la log\u00edstica, el transporte y el stock fue extremadamente importante. La implementaci\u00f3n de soluciones en torno a la visibilidad redujo el coste de demora en el puerto y mejor\u00f3 la gesti\u00f3n de stock en el centro de distribuci\u00f3n. Volver a los t\u00e9rminos FOB (free on board) nos permiti\u00f3 proporcionar \u00f3rdenes de compra y gesti\u00f3n de proveedores en las ubicaciones de abastecimiento de LG Harris en todo el mundo.[\/vc_column_text][vc_column_text el_class=&#8221;boxwhy VinetasRed&#8221;]<img loading=\"lazy\" decoding=\"async\" class=\"text-center\" src=\"\/wp-content\/uploads\/2020\/03\/solution-01-1.svg\" alt=\"\" width=\"60\" height=\"60\" \/><\/p>\n<h2 class=\"parallax-title text-center\">La soluci\u00f3n<\/h2>\n<p>El equipo de Noatum Logistics International Supply Chain dise\u00f1\u00f3 soluciones para contrarrestar los retos a los que LG Harris enfrentaba. A trav\u00e9s de un cuidadoso an\u00e1lisis y cuantificaci\u00f3n de datos, los t\u00e9rminos de venta se cambiaron a FOB en el 90% de la base de suministro. Noatum Logistics implement\u00f3 PowerVIEW, un sistema de gesti\u00f3n de pedidos de compra Web, para proporcionar una mejor y m\u00e1s detallada transparencia de la informaci\u00f3n del env\u00edo. Mediante la consulta de los datos num\u00e9ricos, los planificadores pod\u00edan localizar el inventario en toda la cadena de suministro.<br \/>\nGracias al volumen anual de contenedores y aprovechando sus relaciones con los transportistas, Noatum Logistics pudo proporcionar al cliente una tarifa fija. Ello permiti\u00f3 a LG Harris comprender y controlar mejor sus costes. Con el an\u00e1lisis conjunto de los sistemas de compra del cliente, Noatum Logistics pudo identificar datos importantes en \u00f3rdenes de compra, gestionar de manera efectiva a sus proveedores y elaborar un an\u00e1lisis de KPI consistente y detallado para las business review meetings mensuales establecidas. Gracias a nuestra s\u00f3lida pol\u00edtica de gesti\u00f3n de cuentas, el equipo de LG Harris advirti\u00f3 r\u00e1pidamente el valor a\u00f1adido que supone trabajar con Noatum Logistics.[\/vc_column_text][\/vc_column][\/vc_row][vc_row el_class=&#8221;VinetasRed&#8221;][vc_column][vc_raw_html]PGltZyBzcmM9Ii93cC1jb250ZW50L3VwbG9hZHMvMjAyMC8wMy9yZXN1bHQtMDEuc3ZnIiB3aWR0aD0iODBweCIgLz4=[\/vc_raw_html]<div class=\"zozo-parallax-header\"><div class=\"parallax-header\"><h2 class=\"parallax-title text-center\">El resultado<\/h2><div class=\"parallax-desc default-style text-center\"><p>Como resultado de las soluciones implementadas por Noatum Logistics, LG Harris se benefici\u00f3 r\u00e1pidamente de una reducci\u00f3n del 15% en sus gastos de transporte. Al obtener una mayor visibilidad y una mejor gesti\u00f3n t\u00e1ctica y estrat\u00e9gica de la cuenta, LG Harris pudo controlar las entradas en el centro de distribuci\u00f3n, reduciendo los costes de demora (hasta un 80%) as\u00ed como los costes de horas extras de almac\u00e9n. El cliente tambi\u00e9n experiment\u00f3 una mejora en el speed-to-market y la reposici\u00f3n de productos. Noatum Logistics es ahora un apoyo clave para LG Harris. Esta pr\u00f3spera relaci\u00f3n se expandi\u00f3 y Noatum Logistics se hizo cargo de todas las necesidades de transporte del cliente durante 2015.<\/p>\n<\/div><\/div><\/div>[vc_column_text]<\/p>\n<div class=\"citaasus\">\n<p>Desde que trabajamos con la log\u00edstica de Noatum Logistics, tenemos una transparencia total de nuestra mercanc\u00eda. Incluyendo \u00f3rdenes de compra y gesti\u00f3n de proveedores a un nivel de detalle que no hab\u00edamos experimentado previamente.<br \/>\nEl equipo de Noatum Logistics nos ha proporcionado apoyo y experiencia continua en la gesti\u00f3n de nuestra cadena de suministro entrante y el servicio prestado encaja perfectamente con nuestro negocio. Noatum Logistics ha proporcionado valor a\u00f1adido a nuestro negocio<\/p>\n<div class=\"singin\">MARK POWYS<br \/>\nSUPPLY PLANNING MANAGER<br \/>\nLG HARRIS<\/div>\n<\/div>\n<p>[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Al estudiar las necesidades de la cadena de suministro de LG Harris, Noatum Logistics identific\u00f3 r\u00e1pidamente que sus t\u00e9rminos de compra eran CIF (Cost \u2013 Insurance &#8211; Freight) en la mayor\u00eda de su base de suministro. Esto le imped\u00eda la transparencia total en los env\u00edos hasta que las mercanc\u00edas llegaban al puerto. Contabilizar m\u00e1s de 1.000 TEU por a\u00f1o supon\u00eda un gran dolor de cabeza. El modelo de la cadena de suministro era completamente reactivo con poca o ninguna gesti\u00f3n de informes o indicadores clave de rendimiento (KPI). Esto supon\u00eda altos cargos por demora, inventario entrante y dificultades del control de stocks en el centro de distribuci\u00f3n LG Harris ubicado en Midlands (Reino Unido).<\/p>\n","protected":false},"featured_media":679,"template":"","meta":[],"class_list":["post-674","case_studies","type-case_studies","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Caso de \u00e9xito \u2013 Log\u00edstica para retail: LG Harris | Noatum Logistics<\/title>\n<meta name=\"description\" content=\"Fundada en 1928, Harris es un fabricante de clase mundial de productos de decoraci\u00f3n que utiliza algunos de los mejores materiales y est\u00e1 dise\u00f1ado para facilitar su uso.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.noatumlogistics.com\/esp\/case-studies\/retail-logistics-lg-harris\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Caso de \u00e9xito \u2013 Log\u00edstica para retail: LG Harris | Noatum Logistics\" \/>\n<meta property=\"og:description\" content=\"Fundada en 1928, Harris es un fabricante de clase mundial de productos de decoraci\u00f3n que utiliza algunos de los mejores materiales y est\u00e1 dise\u00f1ado para facilitar su uso.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.noatumlogistics.com\/esp\/case-studies\/retail-logistics-lg-harris\/\" \/>\n<meta property=\"og:site_name\" content=\"Espa\u00f1a\" \/>\n<meta property=\"article:modified_time\" content=\"2021-05-27T14:36:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.noatumlogistics.com\/esp\/wp-content\/uploads\/sites\/7\/2020\/06\/retail-logistics-case-study-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.noatumlogistics.com\\\/esp\\\/case-studies\\\/retail-logistics-lg-harris\\\/\",\"url\":\"https:\\\/\\\/www.noatumlogistics.com\\\/esp\\\/case-studies\\\/retail-logistics-lg-harris\\\/\",\"name\":\"Caso de \u00e9xito \u2013 Log\u00edstica para retail: LG Harris | Noatum Logistics\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.noatumlogistics.com\\\/esp\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.noatumlogistics.com\\\/esp\\\/case-studies\\\/retail-logistics-lg-harris\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.noatumlogistics.com\\\/esp\\\/case-studies\\\/retail-logistics-lg-harris\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.noatumlogistics.com\\\/esp\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2020\\\/06\\\/retail-logistics-case-study-scaled.jpg\",\"datePublished\":\"2020-05-06T14:26:11+00:00\",\"dateModified\":\"2021-05-27T14:36:42+00:00\",\"description\":\"Fundada en 1928, Harris es un fabricante de clase mundial de productos de decoraci\u00f3n que utiliza algunos de los mejores materiales y est\u00e1 dise\u00f1ado para facilitar su uso.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.noatumlogistics.com\\\/esp\\\/case-studies\\\/retail-logistics-lg-harris\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.noatumlogistics.com\\\/esp\\\/case-studies\\\/retail-logistics-lg-harris\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.noatumlogistics.com\\\/esp\\\/case-studies\\\/retail-logistics-lg-harris\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.noatumlogistics.com\\\/esp\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2020\\\/06\\\/retail-logistics-case-study-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.noatumlogistics.com\\\/esp\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2020\\\/06\\\/retail-logistics-case-study-scaled.jpg\",\"width\":2560,\"height\":1440,\"caption\":\"retail logistics case study\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.noatumlogistics.com\\\/esp\\\/case-studies\\\/retail-logistics-lg-harris\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.noatumlogistics.com\\\/esp\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Case Studies\",\"item\":\"https:\\\/\\\/www.noatumlogistics.com\\\/esp\\\/case-studies\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Caso de \u00e9xito \u2013 Log\u00edstica para retail: LG Harris\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.noatumlogistics.com\\\/esp\\\/#website\",\"url\":\"https:\\\/\\\/www.noatumlogistics.com\\\/esp\\\/\",\"name\":\"Espa\u00f1a\",\"description\":\"Just another Noatum Logistics site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.noatumlogistics.com\\\/esp\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Caso de \u00e9xito \u2013 Log\u00edstica para retail: LG Harris | Noatum Logistics","description":"Fundada en 1928, Harris es un fabricante de clase mundial de productos de decoraci\u00f3n que utiliza algunos de los mejores materiales y est\u00e1 dise\u00f1ado para facilitar su uso.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.noatumlogistics.com\/esp\/case-studies\/retail-logistics-lg-harris\/","og_locale":"es_ES","og_type":"article","og_title":"Caso de \u00e9xito \u2013 Log\u00edstica para retail: LG Harris | Noatum Logistics","og_description":"Fundada en 1928, Harris es un fabricante de clase mundial de productos de decoraci\u00f3n que utiliza algunos de los mejores materiales y est\u00e1 dise\u00f1ado para facilitar su uso.","og_url":"https:\/\/www.noatumlogistics.com\/esp\/case-studies\/retail-logistics-lg-harris\/","og_site_name":"Espa\u00f1a","article_modified_time":"2021-05-27T14:36:42+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/www.noatumlogistics.com\/esp\/wp-content\/uploads\/sites\/7\/2020\/06\/retail-logistics-case-study-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.noatumlogistics.com\/esp\/case-studies\/retail-logistics-lg-harris\/","url":"https:\/\/www.noatumlogistics.com\/esp\/case-studies\/retail-logistics-lg-harris\/","name":"Caso de \u00e9xito \u2013 Log\u00edstica para retail: LG Harris | Noatum Logistics","isPartOf":{"@id":"https:\/\/www.noatumlogistics.com\/esp\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.noatumlogistics.com\/esp\/case-studies\/retail-logistics-lg-harris\/#primaryimage"},"image":{"@id":"https:\/\/www.noatumlogistics.com\/esp\/case-studies\/retail-logistics-lg-harris\/#primaryimage"},"thumbnailUrl":"https:\/\/www.noatumlogistics.com\/esp\/wp-content\/uploads\/sites\/7\/2020\/06\/retail-logistics-case-study-scaled.jpg","datePublished":"2020-05-06T14:26:11+00:00","dateModified":"2021-05-27T14:36:42+00:00","description":"Fundada en 1928, Harris es un fabricante de clase mundial de productos de decoraci\u00f3n que utiliza algunos de los mejores materiales y est\u00e1 dise\u00f1ado para facilitar su uso.","breadcrumb":{"@id":"https:\/\/www.noatumlogistics.com\/esp\/case-studies\/retail-logistics-lg-harris\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.noatumlogistics.com\/esp\/case-studies\/retail-logistics-lg-harris\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.noatumlogistics.com\/esp\/case-studies\/retail-logistics-lg-harris\/#primaryimage","url":"https:\/\/www.noatumlogistics.com\/esp\/wp-content\/uploads\/sites\/7\/2020\/06\/retail-logistics-case-study-scaled.jpg","contentUrl":"https:\/\/www.noatumlogistics.com\/esp\/wp-content\/uploads\/sites\/7\/2020\/06\/retail-logistics-case-study-scaled.jpg","width":2560,"height":1440,"caption":"retail logistics case study"},{"@type":"BreadcrumbList","@id":"https:\/\/www.noatumlogistics.com\/esp\/case-studies\/retail-logistics-lg-harris\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.noatumlogistics.com\/esp\/"},{"@type":"ListItem","position":2,"name":"Case Studies","item":"https:\/\/www.noatumlogistics.com\/esp\/case-studies\/"},{"@type":"ListItem","position":3,"name":"Caso de \u00e9xito \u2013 Log\u00edstica para retail: LG Harris"}]},{"@type":"WebSite","@id":"https:\/\/www.noatumlogistics.com\/esp\/#website","url":"https:\/\/www.noatumlogistics.com\/esp\/","name":"Espa\u00f1a","description":"Just another Noatum Logistics site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.noatumlogistics.com\/esp\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/www.noatumlogistics.com\/esp\/wp-json\/wp\/v2\/case_studies\/674","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.noatumlogistics.com\/esp\/wp-json\/wp\/v2\/case_studies"}],"about":[{"href":"https:\/\/www.noatumlogistics.com\/esp\/wp-json\/wp\/v2\/types\/case_studies"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.noatumlogistics.com\/esp\/wp-json\/wp\/v2\/media\/679"}],"wp:attachment":[{"href":"https:\/\/www.noatumlogistics.com\/esp\/wp-json\/wp\/v2\/media?parent=674"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}