{"id":3105,"date":"2022-07-21T14:59:58","date_gmt":"2022-07-21T14:59:58","guid":{"rendered":"https:\/\/www.noatumlogistics.com\/esp\/case-studies\/caso-exito-transporte-aereo-mineria\/"},"modified":"2026-04-28T13:27:34","modified_gmt":"2026-04-28T13:27:34","slug":"caso-exito-transporte-aereo-mineria","status":"publish","type":"case_studies","link":"https:\/\/www.noatumlogistics.com\/esp\/case-studies\/caso-exito-transporte-aereo-mineria\/","title":{"rendered":"Caso de \u00e9xito &#8211; Servicios de transporte a\u00e9reo para la industria minera"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row full_width=&#8221;stretch_row_content_no_spaces&#8221; center_row=&#8221;yes&#8221; css=&#8221;.vc_custom_1584003394864{margin-top: 0px !important;background-image: url(https:\/\/www.noatumlogistics.com\/wp-content\/uploads\/2020\/02\/fondo-directorio-2.jpg?id=9849) !important;background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;}&#8221;][vc_column]<div class=\"zozo-parallax-header\"><div class=\"parallax-header\"><h2 class=\"parallax-title text-center\">Soluci\u00f3n de transporte a\u00e9reo para sector miner\u00eda<\/h2><div class=\"parallax-desc default-style text-center\"><p>Empresa dedicada a la explotaci\u00f3n de yacimientos mineros en Cusco.<\/p>\n<\/div><\/div><\/div>[\/vc_column][\/vc_row][vc_row][vc_column][vc_raw_html css=&#8221;.vc_custom_1588776219005{margin-bottom: 15px !important;}&#8221;]PGltZyBjbGFzcz0iIiB3aWR0aD0iNjBweCIgc3JjPSIvd3AtY29udGVudC91cGxvYWRzLzIwMjAvMDMvY2hhbGxlbmdlLTAxLnN2ZyI+[\/vc_raw_html]<div class=\"zozo-parallax-header\"><div class=\"parallax-header\"><h2 class=\"parallax-title text-center\">El reto<\/h2><div class=\"parallax-desc default-style text-center\"><p>Nuestro cliente necesitaba transportar un total de 8 rollos de cable de 23 toneladas cada uno desde Shangh\u00e1i. El reto era realizar el env\u00edo en el menor tiempo posible con unos costes razonables.<\/p>\n<\/div><\/div><\/div>[vc_gallery type=&#8221;image_grid&#8221; images=&#8221;17611,17609,17607&#8243; img_size=&#8221;350&#8243;][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row_content&#8221; center_row=&#8221;yes&#8221; typo_style=&#8221;light&#8221; bg_type=&#8221;bg_color&#8221; seperator_enable=&#8221;seperator_enable_value&#8221; seperator_type=&#8221;triangle_svg_seperator&#8221; seperator_svg_height=&#8221;35&#8243; el_class=&#8221;redgradientbg&#8221; bg_color_value=&#8221;#dd9933&#8243; css=&#8221;.vc_custom_1583946305078{padding-top: 100px !important;}&#8221;][vc_column][vc_column_text el_class=&#8221;boxwhy&#8221;]<img decoding=\"async\" class=\"text-center\" src=\"https:\/\/www.noatumlogistics.com\/wp-content\/uploads\/2020\/03\/strategy-01-1.svg\" alt=\"\" width=\"50\" \/><\/p>\n<h2 class=\"parallax-title text-center\">La estrategia<\/h2>\n<p>Realizar un env\u00edo mar\u00edtimo desde China a Per\u00fa tiene un tiempo de tr\u00e1nsito que oscila entre los 45-50 d\u00edas. La urgencia en disponer de la mercanc\u00eda para no interrumpir la cadena log\u00edstica de nuestro cliente hizo que el equipo de Noatum Logistics se decantara por el transporte v\u00eda ch\u00e1rter a\u00e9reo.[\/vc_column_text][vc_column_text el_class=&#8221;boxwhy VinetasRed&#8221;]<img loading=\"lazy\" decoding=\"async\" class=\"text-center\" src=\"\/wp-content\/uploads\/2020\/03\/solution-01-1.svg\" alt=\"\" width=\"60\" height=\"60\" \/><\/p>\n<h2 class=\"parallax-title text-center\">La soluci\u00f3n<\/h2>\n<p>Por el proceso de producci\u00f3n, la entrega de los rollos de cable se hac\u00eda de dos en dos unidades y, tan pronto como sal\u00edan de f\u00e1brica, hab\u00eda que trasladarlos hasta Cusco. La mejor soluci\u00f3n por ahorro de tiempo y costes consisti\u00f3 en el transporte v\u00eda Air Part Charter, con la ruta Shangh\u00e1i \u2013 Chicago \u2013 Miami \u2013 Lima. Al tratarse de bultos grandes, que requer\u00edan de una manipulaci\u00f3n especial, se solicit\u00f3 una extensi\u00f3n de zona primaria a aduanas en el aeropuerto de Lima. Los rollos de cable deb\u00edan ser descargados directamente sobre la unidad especial para evitar manipulaciones y las gr\u00faas necesarias para esta operaci\u00f3n no son un equipamiento habitual del aeropuerto, por ello se necesitaba el permiso solicitado para descargar en una zona especialmente habilitada. [\/vc_column_text][\/vc_column][\/vc_row][vc_row el_class=&#8221;VinetasRed&#8221;][vc_column][vc_raw_html]PGltZyB3aWR0aD0iODBweCIgc3JjPSIvd3AtY29udGVudC91cGxvYWRzLzIwMjAvMDMvcmVzdWx0LTAxLnN2ZyI+[\/vc_raw_html]<div class=\"zozo-parallax-header\"><div class=\"parallax-header\"><h2 class=\"parallax-title text-center\">El resultado<\/h2><div class=\"parallax-desc default-style text-center\"><p>Se necesitaron \u00fanicamente 5 d\u00edas para completar la operativa y nuestro cliente recibi\u00f3 la mercanc\u00eda justo en el momento en el que la necesitaba.<\/p>\n<\/div><\/div><\/div>[\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Nuestro cliente necesitaba transportar un total de 8 rollos de cable de 23 toneladas cada uno desde Shangh\u00e1i. El reto era realizar el env\u00edo en el menor tiempo posible con unos costes razonables.<\/p>\n","protected":false},"featured_media":3112,"template":"","meta":[],"class_list":["post-3105","case_studies","type-case_studies","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Caso de \u00e9xito - Servicios de transporte a\u00e9reo para la industria minera | Noatum Logistics<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.noatumlogistics.com\/esp\/case-studies\/caso-exito-transporte-aereo-mineria\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Caso de \u00e9xito - Servicios de transporte a\u00e9reo para la industria minera | Noatum Logistics\" \/>\n<meta property=\"og:description\" content=\"Nuestro cliente necesitaba transportar un total de 8 rollos de cable de 23 toneladas cada uno desde Shangh\u00e1i. El reto era realizar el env\u00edo en el menor tiempo posible con unos costes razonables.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.noatumlogistics.com\/esp\/case-studies\/caso-exito-transporte-aereo-mineria\/\" \/>\n<meta property=\"og:site_name\" content=\"Espa\u00f1a\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-28T13:27:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.noatumlogistics.com\/esp\/wp-content\/uploads\/sites\/7\/2022\/07\/air-transport-mining-industry-services.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.noatumlogistics.com\\\/esp\\\/case-studies\\\/caso-exito-transporte-aereo-mineria\\\/\",\"url\":\"https:\\\/\\\/www.noatumlogistics.com\\\/esp\\\/case-studies\\\/caso-exito-transporte-aereo-mineria\\\/\",\"name\":\"Caso de \u00e9xito - Servicios de transporte a\u00e9reo para la industria minera | Noatum Logistics\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.noatumlogistics.com\\\/esp\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.noatumlogistics.com\\\/esp\\\/case-studies\\\/caso-exito-transporte-aereo-mineria\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.noatumlogistics.com\\\/esp\\\/case-studies\\\/caso-exito-transporte-aereo-mineria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.noatumlogistics.com\\\/esp\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2022\\\/07\\\/air-transport-mining-industry-services.jpg\",\"datePublished\":\"2022-07-21T14:59:58+00:00\",\"dateModified\":\"2026-04-28T13:27:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.noatumlogistics.com\\\/esp\\\/case-studies\\\/caso-exito-transporte-aereo-mineria\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.noatumlogistics.com\\\/esp\\\/case-studies\\\/caso-exito-transporte-aereo-mineria\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.noatumlogistics.com\\\/esp\\\/case-studies\\\/caso-exito-transporte-aereo-mineria\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.noatumlogistics.com\\\/esp\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2022\\\/07\\\/air-transport-mining-industry-services.jpg\",\"contentUrl\":\"https:\\\/\\\/www.noatumlogistics.com\\\/esp\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2022\\\/07\\\/air-transport-mining-industry-services.jpg\",\"width\":1500,\"height\":1000,\"caption\":\"air transport for mining industry\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.noatumlogistics.com\\\/esp\\\/case-studies\\\/caso-exito-transporte-aereo-mineria\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.noatumlogistics.com\\\/esp\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Case Studies\",\"item\":\"https:\\\/\\\/www.noatumlogistics.com\\\/esp\\\/case-studies\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Caso de \u00e9xito &#8211; Servicios de transporte a\u00e9reo para la industria minera\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.noatumlogistics.com\\\/esp\\\/#website\",\"url\":\"https:\\\/\\\/www.noatumlogistics.com\\\/esp\\\/\",\"name\":\"Espa\u00f1a\",\"description\":\"Just another Noatum Logistics site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.noatumlogistics.com\\\/esp\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Caso de \u00e9xito - Servicios de transporte a\u00e9reo para la industria minera | Noatum Logistics","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.noatumlogistics.com\/esp\/case-studies\/caso-exito-transporte-aereo-mineria\/","og_locale":"es_ES","og_type":"article","og_title":"Caso de \u00e9xito - Servicios de transporte a\u00e9reo para la industria minera | Noatum Logistics","og_description":"Nuestro cliente necesitaba transportar un total de 8 rollos de cable de 23 toneladas cada uno desde Shangh\u00e1i. El reto era realizar el env\u00edo en el menor tiempo posible con unos costes razonables.","og_url":"https:\/\/www.noatumlogistics.com\/esp\/case-studies\/caso-exito-transporte-aereo-mineria\/","og_site_name":"Espa\u00f1a","article_modified_time":"2026-04-28T13:27:34+00:00","og_image":[{"width":1500,"height":1000,"url":"https:\/\/www.noatumlogistics.com\/esp\/wp-content\/uploads\/sites\/7\/2022\/07\/air-transport-mining-industry-services.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.noatumlogistics.com\/esp\/case-studies\/caso-exito-transporte-aereo-mineria\/","url":"https:\/\/www.noatumlogistics.com\/esp\/case-studies\/caso-exito-transporte-aereo-mineria\/","name":"Caso de \u00e9xito - Servicios de transporte a\u00e9reo para la industria minera | Noatum Logistics","isPartOf":{"@id":"https:\/\/www.noatumlogistics.com\/esp\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.noatumlogistics.com\/esp\/case-studies\/caso-exito-transporte-aereo-mineria\/#primaryimage"},"image":{"@id":"https:\/\/www.noatumlogistics.com\/esp\/case-studies\/caso-exito-transporte-aereo-mineria\/#primaryimage"},"thumbnailUrl":"https:\/\/www.noatumlogistics.com\/esp\/wp-content\/uploads\/sites\/7\/2022\/07\/air-transport-mining-industry-services.jpg","datePublished":"2022-07-21T14:59:58+00:00","dateModified":"2026-04-28T13:27:34+00:00","breadcrumb":{"@id":"https:\/\/www.noatumlogistics.com\/esp\/case-studies\/caso-exito-transporte-aereo-mineria\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.noatumlogistics.com\/esp\/case-studies\/caso-exito-transporte-aereo-mineria\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.noatumlogistics.com\/esp\/case-studies\/caso-exito-transporte-aereo-mineria\/#primaryimage","url":"https:\/\/www.noatumlogistics.com\/esp\/wp-content\/uploads\/sites\/7\/2022\/07\/air-transport-mining-industry-services.jpg","contentUrl":"https:\/\/www.noatumlogistics.com\/esp\/wp-content\/uploads\/sites\/7\/2022\/07\/air-transport-mining-industry-services.jpg","width":1500,"height":1000,"caption":"air transport for mining industry"},{"@type":"BreadcrumbList","@id":"https:\/\/www.noatumlogistics.com\/esp\/case-studies\/caso-exito-transporte-aereo-mineria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.noatumlogistics.com\/esp\/"},{"@type":"ListItem","position":2,"name":"Case Studies","item":"https:\/\/www.noatumlogistics.com\/esp\/case-studies\/"},{"@type":"ListItem","position":3,"name":"Caso de \u00e9xito &#8211; Servicios de transporte a\u00e9reo para la industria minera"}]},{"@type":"WebSite","@id":"https:\/\/www.noatumlogistics.com\/esp\/#website","url":"https:\/\/www.noatumlogistics.com\/esp\/","name":"Espa\u00f1a","description":"Just another Noatum Logistics site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.noatumlogistics.com\/esp\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/www.noatumlogistics.com\/esp\/wp-json\/wp\/v2\/case_studies\/3105","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.noatumlogistics.com\/esp\/wp-json\/wp\/v2\/case_studies"}],"about":[{"href":"https:\/\/www.noatumlogistics.com\/esp\/wp-json\/wp\/v2\/types\/case_studies"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.noatumlogistics.com\/esp\/wp-json\/wp\/v2\/media\/3112"}],"wp:attachment":[{"href":"https:\/\/www.noatumlogistics.com\/esp\/wp-json\/wp\/v2\/media?parent=3105"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}