{"id":18143,"date":"2022-10-27T13:03:13","date_gmt":"2022-10-27T12:03:13","guid":{"rendered":"https:\/\/www.noatumlogistics.com\/claves-para-establecer-una-cadena-de-suministro-exitosa\/"},"modified":"2022-12-21T09:45:21","modified_gmt":"2022-12-21T08:45:21","slug":"claves-para-establecer-una-cadena-de-suministro-exitosa","status":"publish","type":"post","link":"https:\/\/www.noatumlogistics.com\/es\/claves-para-establecer-una-cadena-de-suministro-exitosa\/","title":{"rendered":"4 claves para establecer una cadena de suministro exitosa"},"content":{"rendered":"<p>En la mayor\u00eda de los casos, los bienes se producen mediante una combinaci\u00f3n de m\u00e9todos. Las empresas deben decidir si es pertinente subcontratar la fabricaci\u00f3n. Esta planificaci\u00f3n de las operaciones es esencial porque estas decisiones influyen en la cadena de suministro. La planificaci\u00f3n tambi\u00e9n implica trazar la red de instalaciones de manufactura y almacenaje, determinar los niveles de producci\u00f3n y especificar los flujos de transporte entre los centros. Tambi\u00e9n implica evaluar c\u00f3mo mejorar la cadena de suministro global y sus procesos de gesti\u00f3n.<br \/>\nUn modelo com\u00fan y muy eficaz es el de Referencia de Operaciones de la Cadena de Suministro (SCOR por sus siglas en ingl\u00e9s), desarrollado por el Consejo de la Cadena de Suministro para que los directivos puedan abordar, mejorar y comunicar eficazmente las pr\u00e1cticas de gesti\u00f3n de la cadena de suministro.<br \/>\nEl modelo SCOR recorre cinco etapas de la cadena de suministro: Planificar, Abastecerse, Fabricar, Entregar, Devolver<br \/>\nEn el pasado, la prioridad en cualquier cadena de suministro era minimizar los residuos para entregar los productos lo m\u00e1s r\u00e1pido posible. Sin embargo, la pandemia de COVID-19 hizo que los l\u00edderes de la cadena de suministro cambiaran su enfoque de la eficiencia a la resiliencia para soportar la volatilidad global.<br \/>\nAumentar la resistencia de la cadena de suministro puede no ser especialmente rentable a corto plazo, pero es un riesgo que muchas organizaciones est\u00e1n dispuestas a asumir para garantizar la rentabilidad a largo plazo.<br \/>\nEs casi imposible predecir cu\u00e1l ser\u00e1 la pr\u00f3xima gran crisis, y precisamente por eso los profesionales de la cadena de suministro est\u00e1n empezando a alejarse del dise\u00f1o de la cadena de suministro ajustada que ha prevalecido durante d\u00e9cadas.<\/p>\n<p>&nbsp;<\/p>\n<h2>Mirar hacia el futuro<\/h2>\n<p>La estrategia de una cadena de suministro no debe centrarse \u00fanicamente en el presente. Mirar hacia el futuro es clave para crecer y escalar. Es importante revisar los datos operativos cada trimestre y ver si sigue en el camino de sus objetivos a largo plazo. Una buena forma de empezar, es tomando en cuenta las siguientes preguntas:<\/p>\n<ul>\n<li>\u00bfQu\u00e9 tendencias econ\u00f3micas o industriales est\u00e1n surgiendo que podr\u00edan perturbar su sector o su negocio?<\/li>\n<li>\u00bfHay alguna tecnolog\u00eda que se est\u00e9 desarrollando o que est\u00e9 entrando en el mercado y que pueda ayudar a dar una ventaja a su empresa?<\/li>\n<li>\u00bfEst\u00e1 alcanzando sus KPI? Si no es as\u00ed, \u00bfqu\u00e9 medidas deber\u00eda tomar para completarlo?<\/li>\n<li>\u00bfSu actual red de 3PL est\u00e1 a la altura de la demanda de su mercado?<\/li>\n<\/ul>\n<p>A partir de las respuestas a estas preguntas se podr\u00e1 elaborar un plan para responder de forma proactiva a las tendencias que afectan a la cadena de suministro. Este plan debe tambi\u00e9n incluir cualquier inversi\u00f3n tecnol\u00f3gica necesaria a largo plazo, de modo que est\u00e9 preparado para competir a medida que cambia el mercado.<\/p>\n<p>&nbsp;<\/p>\n<h2>Reducir riesgos<\/h2>\n<p>No existe una cadena de suministro &#8220;libre de riesgos&#8221;. La complejidad de las cadenas de suministro las hace intr\u00ednsecamente vulnerables a factores que escapan al control de la organizaci\u00f3n. Sin embargo, la incorporaci\u00f3n de las estrategias anteriores a su proceso de planificaci\u00f3n puede mejorar la sostenibilidad y minimizar el impacto de las interferencias, si es que se producen.<\/p>\n<p>&nbsp;<\/p>\n<h2>Estandarizar procesos<\/h2>\n<p>Cuanto m\u00e1s coherentes sean las operaciones de una cadena de suministro, m\u00e1s fiable ser\u00e1. Esto es especialmente cierto para las organizaciones cuyos proveedores y fabricantes est\u00e1n dispersos por todo el mundo.<br \/>\nLas plantillas para las plataformas, los productos y las plantas permiten una producci\u00f3n sin fisuras y el cumplimiento de las normas. Por ejemplo, las empresas del sector de la automoci\u00f3n utilizan plataformas de veh\u00edculos comunes para armonizar su estrategia de cadena de suministro.<\/p>\n<h2>Promover redes de colaboraci\u00f3n<\/h2>\n<p>El impacto positivo de una empresa sostenible en el medio ambiente puede multiplicarse mediante la colaboraci\u00f3n entre todas las empresas del sector o incluso entre sectores. Las empresas de un mismo sector pueden tener cadenas de suministro compartidas. La colaboraci\u00f3n entre empresas sobre cuestiones de sostenibilidad en la gesti\u00f3n de la cadena de suministro promover\u00e1 la evoluci\u00f3n de normas y procesos de sostenibilidad ecol\u00f3gicos.<br \/>\nLa colaboraci\u00f3n entre sectores ayuda a reciclar y reutilizar los productos una vez que han cumplido su funci\u00f3n principal. La reutilizaci\u00f3n de los materiales desechados contribuye al reciclaje y promueve la sostenibilidad de la cadena de suministro.<\/p>\n<p>&nbsp;<\/p>\n<p>Establecer una cadena de suministro exitosa no es una acci\u00f3n puntual. Los par\u00e1metros de referencia evolucionan, las m\u00e9tricas deben afinarse, la formaci\u00f3n debe ser continua y todo el proceso necesita repetidos ajustes. Las cadenas de suministro sostenibles no s\u00f3lo tienen un impacto medioambiental, sino que tambi\u00e9n tienen un impacto en el negocio, al ayudar a reducir los costes operativos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En la mayor\u00eda de los casos, los bienes se producen mediante una combinaci\u00f3n de m\u00e9todos. Las empresas deben decidir si es pertinente subcontratar la fabricaci\u00f3n. Esta planificaci\u00f3n de las operaciones&#8230;<\/p>\n","protected":false},"author":9,"featured_media":18141,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[369,350,1],"tags":[],"class_list":["post-18143","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-featured","category-logistics-and-distribution","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>4 claves para establecer una cadena de suministro exitosa | Noatum Logistics<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.noatumlogistics.com\/es\/claves-para-establecer-una-cadena-de-suministro-exitosa\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"4 claves para establecer una cadena de suministro exitosa | Noatum Logistics\" \/>\n<meta property=\"og:description\" content=\"En la mayor\u00eda de los casos, los bienes se producen mediante una combinaci\u00f3n de m\u00e9todos. Las empresas deben decidir si es pertinente subcontratar la fabricaci\u00f3n. Esta planificaci\u00f3n de las operaciones...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.noatumlogistics.com\/es\/claves-para-establecer-una-cadena-de-suministro-exitosa\/\" \/>\n<meta property=\"og:site_name\" content=\"Global\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-27T12:03:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-21T08:45:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.noatumlogistics.com\/wp-content\/uploads\/2022\/10\/27-10-NL.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1170\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mjgutierrez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"mjgutierrez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.noatumlogistics.com\\\/es\\\/claves-para-establecer-una-cadena-de-suministro-exitosa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.noatumlogistics.com\\\/es\\\/claves-para-establecer-una-cadena-de-suministro-exitosa\\\/\"},\"author\":{\"name\":\"mjgutierrez\",\"@id\":\"https:\\\/\\\/www.noatumlogistics.com\\\/es\\\/#\\\/schema\\\/person\\\/a5f444bdf058b79e15d5d0ac335ce513\"},\"headline\":\"4 claves para establecer una cadena de suministro exitosa\",\"datePublished\":\"2022-10-27T12:03:13+00:00\",\"dateModified\":\"2022-12-21T08:45:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.noatumlogistics.com\\\/es\\\/claves-para-establecer-una-cadena-de-suministro-exitosa\\\/\"},\"wordCount\":825,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.noatumlogistics.com\\\/es\\\/claves-para-establecer-una-cadena-de-suministro-exitosa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.noatumlogistics.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/27-10-NL.jpg\",\"articleSection\":[\"Featured\",\"Logistics and distribution\",\"Noticias N\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.noatumlogistics.com\\\/es\\\/claves-para-establecer-una-cadena-de-suministro-exitosa\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.noatumlogistics.com\\\/es\\\/claves-para-establecer-una-cadena-de-suministro-exitosa\\\/\",\"url\":\"https:\\\/\\\/www.noatumlogistics.com\\\/es\\\/claves-para-establecer-una-cadena-de-suministro-exitosa\\\/\",\"name\":\"4 claves para establecer una cadena de suministro exitosa | Noatum Logistics\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.noatumlogistics.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.noatumlogistics.com\\\/es\\\/claves-para-establecer-una-cadena-de-suministro-exitosa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.noatumlogistics.com\\\/es\\\/claves-para-establecer-una-cadena-de-suministro-exitosa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.noatumlogistics.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/27-10-NL.jpg\",\"datePublished\":\"2022-10-27T12:03:13+00:00\",\"dateModified\":\"2022-12-21T08:45:21+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.noatumlogistics.com\\\/es\\\/#\\\/schema\\\/person\\\/a5f444bdf058b79e15d5d0ac335ce513\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.noatumlogistics.com\\\/es\\\/claves-para-establecer-una-cadena-de-suministro-exitosa\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.noatumlogistics.com\\\/es\\\/claves-para-establecer-una-cadena-de-suministro-exitosa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.noatumlogistics.com\\\/es\\\/claves-para-establecer-una-cadena-de-suministro-exitosa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.noatumlogistics.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/27-10-NL.jpg\",\"contentUrl\":\"https:\\\/\\\/www.noatumlogistics.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/27-10-NL.jpg\",\"width\":1170,\"height\":500,\"caption\":\"supply chain\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.noatumlogistics.com\\\/es\\\/claves-para-establecer-una-cadena-de-suministro-exitosa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.noatumlogistics.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Log\u00edstica y distribuci\u00f3n\",\"item\":\"https:\\\/\\\/www.noatumlogistics.com\\\/es\\\/articulos-logistica-distribucion\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"4 claves para establecer una cadena de suministro exitosa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.noatumlogistics.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.noatumlogistics.com\\\/es\\\/\",\"name\":\"Global\",\"description\":\"Excelencia en servicios log\u00edsticos\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.noatumlogistics.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.noatumlogistics.com\\\/es\\\/#\\\/schema\\\/person\\\/a5f444bdf058b79e15d5d0ac335ce513\",\"name\":\"mjgutierrez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1eb2c9a609440e74fcaa5729c2a5afcfcba6eb3701b019a67f10340c7b330b09?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1eb2c9a609440e74fcaa5729c2a5afcfcba6eb3701b019a67f10340c7b330b09?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1eb2c9a609440e74fcaa5729c2a5afcfcba6eb3701b019a67f10340c7b330b09?s=96&d=mm&r=g\",\"caption\":\"mjgutierrez\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"4 claves para establecer una cadena de suministro exitosa | Noatum Logistics","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.noatumlogistics.com\/es\/claves-para-establecer-una-cadena-de-suministro-exitosa\/","og_locale":"es_ES","og_type":"article","og_title":"4 claves para establecer una cadena de suministro exitosa | Noatum Logistics","og_description":"En la mayor\u00eda de los casos, los bienes se producen mediante una combinaci\u00f3n de m\u00e9todos. Las empresas deben decidir si es pertinente subcontratar la fabricaci\u00f3n. Esta planificaci\u00f3n de las operaciones...","og_url":"https:\/\/www.noatumlogistics.com\/es\/claves-para-establecer-una-cadena-de-suministro-exitosa\/","og_site_name":"Global","article_published_time":"2022-10-27T12:03:13+00:00","article_modified_time":"2022-12-21T08:45:21+00:00","og_image":[{"width":1170,"height":500,"url":"https:\/\/www.noatumlogistics.com\/wp-content\/uploads\/2022\/10\/27-10-NL.jpg","type":"image\/jpeg"}],"author":"mjgutierrez","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"mjgutierrez","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.noatumlogistics.com\/es\/claves-para-establecer-una-cadena-de-suministro-exitosa\/#article","isPartOf":{"@id":"https:\/\/www.noatumlogistics.com\/es\/claves-para-establecer-una-cadena-de-suministro-exitosa\/"},"author":{"name":"mjgutierrez","@id":"https:\/\/www.noatumlogistics.com\/es\/#\/schema\/person\/a5f444bdf058b79e15d5d0ac335ce513"},"headline":"4 claves para establecer una cadena de suministro exitosa","datePublished":"2022-10-27T12:03:13+00:00","dateModified":"2022-12-21T08:45:21+00:00","mainEntityOfPage":{"@id":"https:\/\/www.noatumlogistics.com\/es\/claves-para-establecer-una-cadena-de-suministro-exitosa\/"},"wordCount":825,"commentCount":0,"image":{"@id":"https:\/\/www.noatumlogistics.com\/es\/claves-para-establecer-una-cadena-de-suministro-exitosa\/#primaryimage"},"thumbnailUrl":"https:\/\/www.noatumlogistics.com\/wp-content\/uploads\/2022\/10\/27-10-NL.jpg","articleSection":["Featured","Logistics and distribution","Noticias N"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.noatumlogistics.com\/es\/claves-para-establecer-una-cadena-de-suministro-exitosa\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.noatumlogistics.com\/es\/claves-para-establecer-una-cadena-de-suministro-exitosa\/","url":"https:\/\/www.noatumlogistics.com\/es\/claves-para-establecer-una-cadena-de-suministro-exitosa\/","name":"4 claves para establecer una cadena de suministro exitosa | Noatum Logistics","isPartOf":{"@id":"https:\/\/www.noatumlogistics.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.noatumlogistics.com\/es\/claves-para-establecer-una-cadena-de-suministro-exitosa\/#primaryimage"},"image":{"@id":"https:\/\/www.noatumlogistics.com\/es\/claves-para-establecer-una-cadena-de-suministro-exitosa\/#primaryimage"},"thumbnailUrl":"https:\/\/www.noatumlogistics.com\/wp-content\/uploads\/2022\/10\/27-10-NL.jpg","datePublished":"2022-10-27T12:03:13+00:00","dateModified":"2022-12-21T08:45:21+00:00","author":{"@id":"https:\/\/www.noatumlogistics.com\/es\/#\/schema\/person\/a5f444bdf058b79e15d5d0ac335ce513"},"breadcrumb":{"@id":"https:\/\/www.noatumlogistics.com\/es\/claves-para-establecer-una-cadena-de-suministro-exitosa\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.noatumlogistics.com\/es\/claves-para-establecer-una-cadena-de-suministro-exitosa\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.noatumlogistics.com\/es\/claves-para-establecer-una-cadena-de-suministro-exitosa\/#primaryimage","url":"https:\/\/www.noatumlogistics.com\/wp-content\/uploads\/2022\/10\/27-10-NL.jpg","contentUrl":"https:\/\/www.noatumlogistics.com\/wp-content\/uploads\/2022\/10\/27-10-NL.jpg","width":1170,"height":500,"caption":"supply chain"},{"@type":"BreadcrumbList","@id":"https:\/\/www.noatumlogistics.com\/es\/claves-para-establecer-una-cadena-de-suministro-exitosa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.noatumlogistics.com\/es\/"},{"@type":"ListItem","position":2,"name":"Log\u00edstica y distribuci\u00f3n","item":"https:\/\/www.noatumlogistics.com\/es\/articulos-logistica-distribucion\/"},{"@type":"ListItem","position":3,"name":"4 claves para establecer una cadena de suministro exitosa"}]},{"@type":"WebSite","@id":"https:\/\/www.noatumlogistics.com\/es\/#website","url":"https:\/\/www.noatumlogistics.com\/es\/","name":"Global","description":"Excelencia en servicios log\u00edsticos","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.noatumlogistics.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.noatumlogistics.com\/es\/#\/schema\/person\/a5f444bdf058b79e15d5d0ac335ce513","name":"mjgutierrez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/1eb2c9a609440e74fcaa5729c2a5afcfcba6eb3701b019a67f10340c7b330b09?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1eb2c9a609440e74fcaa5729c2a5afcfcba6eb3701b019a67f10340c7b330b09?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1eb2c9a609440e74fcaa5729c2a5afcfcba6eb3701b019a67f10340c7b330b09?s=96&d=mm&r=g","caption":"mjgutierrez"}}]}},"_links":{"self":[{"href":"https:\/\/www.noatumlogistics.com\/es\/wp-json\/wp\/v2\/posts\/18143","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.noatumlogistics.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.noatumlogistics.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.noatumlogistics.com\/es\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.noatumlogistics.com\/es\/wp-json\/wp\/v2\/comments?post=18143"}],"version-history":[{"count":1,"href":"https:\/\/www.noatumlogistics.com\/es\/wp-json\/wp\/v2\/posts\/18143\/revisions"}],"predecessor-version":[{"id":18146,"href":"https:\/\/www.noatumlogistics.com\/es\/wp-json\/wp\/v2\/posts\/18143\/revisions\/18146"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.noatumlogistics.com\/es\/wp-json\/wp\/v2\/media\/18141"}],"wp:attachment":[{"href":"https:\/\/www.noatumlogistics.com\/es\/wp-json\/wp\/v2\/media?parent=18143"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.noatumlogistics.com\/es\/wp-json\/wp\/v2\/categories?post=18143"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.noatumlogistics.com\/es\/wp-json\/wp\/v2\/tags?post=18143"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}