{"id":17279,"date":"2022-02-23T10:42:06","date_gmt":"2022-02-23T09:42:06","guid":{"rendered":"https:\/\/www.noatumlogistics.com\/?p=17279"},"modified":"2022-12-21T09:54:56","modified_gmt":"2022-12-21T08:54:56","slug":"como-optimizar-procesos-de-envio-entrega-de-pedidos","status":"publish","type":"post","link":"https:\/\/www.noatumlogistics.com\/es\/como-optimizar-procesos-de-envio-entrega-de-pedidos\/","title":{"rendered":"C\u00f3mo optimizar los procesos de env\u00edo y entrega de pedidos"},"content":{"rendered":"<p>Lograr una entrega a tiempo es clave para construir relaciones s\u00f3lidas con tus clientes. <strong>Hoy el tiempo tiene m\u00e1s valor que nunca y las exigencias son cada vez m\u00e1s altas. <\/strong>La rapidez en la entrega es uno de los factores m\u00e1s valorados por los clientes en el momento de seleccionar y comprar un producto o servicio, y dar un servicio \u00e1gil es un punto de diferenciaci\u00f3n muy importante para las tiendas online.<\/p>\n<p>&nbsp;<\/p>\n<p>Optimizar los tiempos para lograr las entregas a tiempo de los productos no es tarea f\u00e1cil <strong>y requiere de un trabajo de planificaci\u00f3n riguroso<\/strong>. Vamos a dar algunas claves para alcanzar este objetivo:<\/p>\n<ol>\n<li><strong>Optimizar las rutas<br \/>\n<\/strong>Es importante planificar las rutas de entrega \u00f3ptimas analizando las diferentes variables que pueden afectar la gesti\u00f3n del tiempo y la rapidez de la entrega: tr\u00e1fico, condiciones de las v\u00edas, atascos, etc.\u00a0En la planificaci\u00f3n tambi\u00e9n es clave tener en cuenta los tiempos de carga y descarga, aprovechar los viajes de retorno de los veh\u00edculos\u2026 El objetivo debe ser reducir los tiempos de entrega, atender la mayor cantidad posible de clientes por d\u00eda, recorrer menos kil\u00f3metros, consumir menos combustible y liberar a los transportistas m\u00e1s r\u00e1pido.<\/li>\n<li><strong>Digitalizar los procesos<br \/>\n<\/strong>Las nuevas tecnolog\u00edas deben integrarse en la cadena log\u00edstica para ayudar a reducir los tiempos de entrega. Los ITS (Sistemas Inteligentes de Transporte) cubren un amplio grupo de tecnolog\u00eda, por ejemplo, los sistemas de informaci\u00f3n y localizaci\u00f3n geogr\u00e1fica como el GPS, las aplicaciones inform\u00e1ticas para el c\u00e1lculo de rutas eficientes, el control por voz, etc. Para conseguir la mejor log\u00edstica de entrega de producto hoy en d\u00eda hay que estar atento a la innovaci\u00f3n tecnol\u00f3gica que se produce permanentemente.<\/li>\n<li><strong>Analizar los patrones de demanda repetitivos<\/strong><br \/>\nIdentificar los patrones de demanda c\u00edclicos y predecibles es una t\u00e1ctica clave para optimizar la respuesta log\u00edstica. El an\u00e1lisis de los patrones de demanda permite a la empresa anticiparse para contar con los recursos adecuados y dar una respuesta m\u00e1s \u00e1gil a estas oscilaciones peri\u00f3dicas.<\/li>\n<li><strong>Dar prioridad a la experiencia del cliente<br \/>\n<\/strong>Ofrecer a los clientes una experiencia de compra y recepci\u00f3n de productos satisfactoria es fundamental para su fidelizaci\u00f3n y para convertirlos en prescriptores de la marca. Debe existir un canal de comunicaci\u00f3n siempre abierto para resolver cualquier duda o queja con diligencia y detectar oportunidades de mejora.<\/li>\n<\/ol>\n<p><strong>\u00a0<\/strong><\/p>\n<h2>C\u00f3mo optimizar la gesti\u00f3n de pedidos en tu e-commerce<\/h2>\n<p><strong>El trabajo comienza en el momento en que un cliente paga por un producto en la tienda online<\/strong>: hay que comunicar el pedido al almac\u00e9n, localizar el producto, embalarlo, enviarlo y transportarlo hasta su destino final.<\/p>\n<p>Muchas empresas gestionan los pedidos directamente desde la plataforma de ecommerce, pero con vol\u00famenes grandes de negocio lo ideal es conectar la tienda online con el software ERP de la empresa. Con un OMS (Order Management System) no conectado con el ERP al final hay que introducir informaci\u00f3n manualmente. Esto es claramente un proceso ineficiente que multiplica el tiempo que tienes que dedicar a la gesti\u00f3n de cada pedido. <strong>Hay que trabajar para reducir al m\u00e1ximo las duplicidades y los tiempos muertos provocados por flujos de trabajo ineficaces.<\/strong><\/p>\n<p>Los productos deber\u00e1n estar correctamente etiquetados y codificados para que sean f\u00e1cilmente localizables. Los procesos de gesti\u00f3n en el almac\u00e9n deben tener un protocolo claro.<strong> El almac\u00e9n debe disponer de acceso a los pedidos en tiempo real para que se puedan implementar procesos \u00e1giles y adecuados a las necesidades del cliente. <\/strong><\/p>\n<p>El inventario debe <strong>mantener siempre un stock m\u00ednimo de los productos de m\u00e1s rotaci\u00f3n<\/strong>. Un producto agotado supone perder la venta de algunos pedidos.<\/p>\n<p>&nbsp;<\/p>\n<h2>Conclusiones<\/h2>\n<p>La <strong>log\u00edstica de entrega de producto<\/strong> es un factor que toda empresa debe considerar para ser competitiva. Para lograrlo, una opci\u00f3n es contratar un <a href=\"https:\/\/www.noatumlogistics.com\/es\/servicio-fulfillment-alta-excelencia-caso-exito\/\">servicio Fulfillment de alta excelencia<\/a> como el de Noatum.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lograr una entrega a tiempo es clave para construir relaciones s\u00f3lidas con tus clientes. Hoy el tiempo tiene m\u00e1s valor que nunca y las exigencias son cada vez m\u00e1s altas&#8230;.<\/p>\n","protected":false},"author":9,"featured_media":17277,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[351],"tags":[],"class_list":["post-17279","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-articulos-logistica-distribucion"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>C\u00f3mo optimizar los procesos de env\u00edo y entrega de pedidos | Noatum Logistics<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.noatumlogistics.com\/es\/como-optimizar-procesos-de-envio-entrega-de-pedidos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"C\u00f3mo optimizar los procesos de env\u00edo y entrega de pedidos | Noatum Logistics\" \/>\n<meta property=\"og:description\" content=\"Lograr una entrega a tiempo es clave para construir relaciones s\u00f3lidas con tus clientes. Hoy el tiempo tiene m\u00e1s valor que nunca y las exigencias son cada vez m\u00e1s altas....\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.noatumlogistics.com\/es\/como-optimizar-procesos-de-envio-entrega-de-pedidos\/\" \/>\n<meta property=\"og:site_name\" content=\"Global\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-23T09:42:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-21T08:54:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.noatumlogistics.com\/wp-content\/uploads\/2022\/02\/fast-delivery.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1170\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mjgutierrez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"mjgutierrez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.noatumlogistics.com\\\/es\\\/como-optimizar-procesos-de-envio-entrega-de-pedidos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.noatumlogistics.com\\\/es\\\/como-optimizar-procesos-de-envio-entrega-de-pedidos\\\/\"},\"author\":{\"name\":\"mjgutierrez\",\"@id\":\"https:\\\/\\\/www.noatumlogistics.com\\\/es\\\/#\\\/schema\\\/person\\\/a5f444bdf058b79e15d5d0ac335ce513\"},\"headline\":\"C\u00f3mo optimizar los procesos de env\u00edo y entrega de pedidos\",\"datePublished\":\"2022-02-23T09:42:06+00:00\",\"dateModified\":\"2022-12-21T08:54:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.noatumlogistics.com\\\/es\\\/como-optimizar-procesos-de-envio-entrega-de-pedidos\\\/\"},\"wordCount\":692,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.noatumlogistics.com\\\/es\\\/como-optimizar-procesos-de-envio-entrega-de-pedidos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.noatumlogistics.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/fast-delivery.jpg\",\"articleSection\":[\"Log\u00edstica y distribuci\u00f3n\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.noatumlogistics.com\\\/es\\\/como-optimizar-procesos-de-envio-entrega-de-pedidos\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.noatumlogistics.com\\\/es\\\/como-optimizar-procesos-de-envio-entrega-de-pedidos\\\/\",\"url\":\"https:\\\/\\\/www.noatumlogistics.com\\\/es\\\/como-optimizar-procesos-de-envio-entrega-de-pedidos\\\/\",\"name\":\"C\u00f3mo optimizar los procesos de env\u00edo y entrega de pedidos | Noatum Logistics\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.noatumlogistics.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.noatumlogistics.com\\\/es\\\/como-optimizar-procesos-de-envio-entrega-de-pedidos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.noatumlogistics.com\\\/es\\\/como-optimizar-procesos-de-envio-entrega-de-pedidos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.noatumlogistics.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/fast-delivery.jpg\",\"datePublished\":\"2022-02-23T09:42:06+00:00\",\"dateModified\":\"2022-12-21T08:54:56+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.noatumlogistics.com\\\/es\\\/#\\\/schema\\\/person\\\/a5f444bdf058b79e15d5d0ac335ce513\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.noatumlogistics.com\\\/es\\\/como-optimizar-procesos-de-envio-entrega-de-pedidos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.noatumlogistics.com\\\/es\\\/como-optimizar-procesos-de-envio-entrega-de-pedidos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.noatumlogistics.com\\\/es\\\/como-optimizar-procesos-de-envio-entrega-de-pedidos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.noatumlogistics.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/fast-delivery.jpg\",\"contentUrl\":\"https:\\\/\\\/www.noatumlogistics.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/fast-delivery.jpg\",\"width\":1170,\"height\":500,\"caption\":\"fast delivery\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.noatumlogistics.com\\\/es\\\/como-optimizar-procesos-de-envio-entrega-de-pedidos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.noatumlogistics.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Log\u00edstica y distribuci\u00f3n\",\"item\":\"https:\\\/\\\/www.noatumlogistics.com\\\/es\\\/articulos-logistica-distribucion\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"C\u00f3mo optimizar los procesos de env\u00edo y entrega de pedidos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.noatumlogistics.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.noatumlogistics.com\\\/es\\\/\",\"name\":\"Global\",\"description\":\"Excelencia en servicios log\u00edsticos\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.noatumlogistics.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.noatumlogistics.com\\\/es\\\/#\\\/schema\\\/person\\\/a5f444bdf058b79e15d5d0ac335ce513\",\"name\":\"mjgutierrez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1eb2c9a609440e74fcaa5729c2a5afcfcba6eb3701b019a67f10340c7b330b09?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1eb2c9a609440e74fcaa5729c2a5afcfcba6eb3701b019a67f10340c7b330b09?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1eb2c9a609440e74fcaa5729c2a5afcfcba6eb3701b019a67f10340c7b330b09?s=96&d=mm&r=g\",\"caption\":\"mjgutierrez\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"C\u00f3mo optimizar los procesos de env\u00edo y entrega de pedidos | Noatum Logistics","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.noatumlogistics.com\/es\/como-optimizar-procesos-de-envio-entrega-de-pedidos\/","og_locale":"es_ES","og_type":"article","og_title":"C\u00f3mo optimizar los procesos de env\u00edo y entrega de pedidos | Noatum Logistics","og_description":"Lograr una entrega a tiempo es clave para construir relaciones s\u00f3lidas con tus clientes. Hoy el tiempo tiene m\u00e1s valor que nunca y las exigencias son cada vez m\u00e1s altas....","og_url":"https:\/\/www.noatumlogistics.com\/es\/como-optimizar-procesos-de-envio-entrega-de-pedidos\/","og_site_name":"Global","article_published_time":"2022-02-23T09:42:06+00:00","article_modified_time":"2022-12-21T08:54:56+00:00","og_image":[{"width":1170,"height":500,"url":"https:\/\/www.noatumlogistics.com\/wp-content\/uploads\/2022\/02\/fast-delivery.jpg","type":"image\/jpeg"}],"author":"mjgutierrez","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"mjgutierrez","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.noatumlogistics.com\/es\/como-optimizar-procesos-de-envio-entrega-de-pedidos\/#article","isPartOf":{"@id":"https:\/\/www.noatumlogistics.com\/es\/como-optimizar-procesos-de-envio-entrega-de-pedidos\/"},"author":{"name":"mjgutierrez","@id":"https:\/\/www.noatumlogistics.com\/es\/#\/schema\/person\/a5f444bdf058b79e15d5d0ac335ce513"},"headline":"C\u00f3mo optimizar los procesos de env\u00edo y entrega de pedidos","datePublished":"2022-02-23T09:42:06+00:00","dateModified":"2022-12-21T08:54:56+00:00","mainEntityOfPage":{"@id":"https:\/\/www.noatumlogistics.com\/es\/como-optimizar-procesos-de-envio-entrega-de-pedidos\/"},"wordCount":692,"commentCount":0,"image":{"@id":"https:\/\/www.noatumlogistics.com\/es\/como-optimizar-procesos-de-envio-entrega-de-pedidos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.noatumlogistics.com\/wp-content\/uploads\/2022\/02\/fast-delivery.jpg","articleSection":["Log\u00edstica y distribuci\u00f3n"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.noatumlogistics.com\/es\/como-optimizar-procesos-de-envio-entrega-de-pedidos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.noatumlogistics.com\/es\/como-optimizar-procesos-de-envio-entrega-de-pedidos\/","url":"https:\/\/www.noatumlogistics.com\/es\/como-optimizar-procesos-de-envio-entrega-de-pedidos\/","name":"C\u00f3mo optimizar los procesos de env\u00edo y entrega de pedidos | Noatum Logistics","isPartOf":{"@id":"https:\/\/www.noatumlogistics.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.noatumlogistics.com\/es\/como-optimizar-procesos-de-envio-entrega-de-pedidos\/#primaryimage"},"image":{"@id":"https:\/\/www.noatumlogistics.com\/es\/como-optimizar-procesos-de-envio-entrega-de-pedidos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.noatumlogistics.com\/wp-content\/uploads\/2022\/02\/fast-delivery.jpg","datePublished":"2022-02-23T09:42:06+00:00","dateModified":"2022-12-21T08:54:56+00:00","author":{"@id":"https:\/\/www.noatumlogistics.com\/es\/#\/schema\/person\/a5f444bdf058b79e15d5d0ac335ce513"},"breadcrumb":{"@id":"https:\/\/www.noatumlogistics.com\/es\/como-optimizar-procesos-de-envio-entrega-de-pedidos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.noatumlogistics.com\/es\/como-optimizar-procesos-de-envio-entrega-de-pedidos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.noatumlogistics.com\/es\/como-optimizar-procesos-de-envio-entrega-de-pedidos\/#primaryimage","url":"https:\/\/www.noatumlogistics.com\/wp-content\/uploads\/2022\/02\/fast-delivery.jpg","contentUrl":"https:\/\/www.noatumlogistics.com\/wp-content\/uploads\/2022\/02\/fast-delivery.jpg","width":1170,"height":500,"caption":"fast delivery"},{"@type":"BreadcrumbList","@id":"https:\/\/www.noatumlogistics.com\/es\/como-optimizar-procesos-de-envio-entrega-de-pedidos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.noatumlogistics.com\/es\/"},{"@type":"ListItem","position":2,"name":"Log\u00edstica y distribuci\u00f3n","item":"https:\/\/www.noatumlogistics.com\/es\/articulos-logistica-distribucion\/"},{"@type":"ListItem","position":3,"name":"C\u00f3mo optimizar los procesos de env\u00edo y entrega de pedidos"}]},{"@type":"WebSite","@id":"https:\/\/www.noatumlogistics.com\/es\/#website","url":"https:\/\/www.noatumlogistics.com\/es\/","name":"Global","description":"Excelencia en servicios log\u00edsticos","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.noatumlogistics.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.noatumlogistics.com\/es\/#\/schema\/person\/a5f444bdf058b79e15d5d0ac335ce513","name":"mjgutierrez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/1eb2c9a609440e74fcaa5729c2a5afcfcba6eb3701b019a67f10340c7b330b09?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1eb2c9a609440e74fcaa5729c2a5afcfcba6eb3701b019a67f10340c7b330b09?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1eb2c9a609440e74fcaa5729c2a5afcfcba6eb3701b019a67f10340c7b330b09?s=96&d=mm&r=g","caption":"mjgutierrez"}}]}},"_links":{"self":[{"href":"https:\/\/www.noatumlogistics.com\/es\/wp-json\/wp\/v2\/posts\/17279","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.noatumlogistics.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.noatumlogistics.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.noatumlogistics.com\/es\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.noatumlogistics.com\/es\/wp-json\/wp\/v2\/comments?post=17279"}],"version-history":[{"count":1,"href":"https:\/\/www.noatumlogistics.com\/es\/wp-json\/wp\/v2\/posts\/17279\/revisions"}],"predecessor-version":[{"id":17283,"href":"https:\/\/www.noatumlogistics.com\/es\/wp-json\/wp\/v2\/posts\/17279\/revisions\/17283"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.noatumlogistics.com\/es\/wp-json\/wp\/v2\/media\/17277"}],"wp:attachment":[{"href":"https:\/\/www.noatumlogistics.com\/es\/wp-json\/wp\/v2\/media?parent=17279"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.noatumlogistics.com\/es\/wp-json\/wp\/v2\/categories?post=17279"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.noatumlogistics.com\/es\/wp-json\/wp\/v2\/tags?post=17279"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}